{"id":59355,"date":"2024-10-23T19:22:54","date_gmt":"2024-10-23T17:22:54","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=59355"},"modified":"2024-10-23T19:32:12","modified_gmt":"2024-10-23T17:32:12","slug":"alveola-la-cite-des-abeilles","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2024\/10\/23\/alveola-la-cite-des-abeilles\/","title":{"rendered":"Alv\u00e9ola La Cit\u00e9 des Abeilles"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"372\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles.jpg\" alt=\"\" class=\"wp-image-59356\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles.jpg 372w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-320x320.jpg 320w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-576x1024.jpeg\" alt=\"\" class=\"wp-image-59357\" style=\"width:138px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-576x1024.jpeg 576w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-169x300.jpeg 169w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-768x1365.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-864x1536.jpeg 864w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-1152x2048.jpeg 1152w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/IMG-20240810-WA0005-1-2-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/div>\n\n\n<p class=\"has-vivid-red-color has-text-color has-link-color wp-elements-e7a646a46e91e22ce19abf746b2f7029\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\"><strong>Martine<\/strong><\/mark><strong>: 8\/10<\/strong><\/p>\n\n\n\n<p>Alveola est le tout premier jeu d&rsquo;une nouvelle maison d&rsquo;\u00e9dition cr\u00e9\u00e9e il y a deux ans Two Manta. Ils ont depuis sorti deux autres jeux: Spring Festival et le tout r\u00e9cent&nbsp;Stickers. Thomas Favreliere, l&rsquo;auteur en est aussi \u00e0 son premier essai. Et c&rsquo;est r\u00e9ussi,&nbsp; le jeu a en effet obtenu le troph\u00e9e Flip en 2022.<\/p>\n\n\n\n<p>Alveola La Cit\u00e9 des Abeilles vous demande de construire une ruche et d&rsquo;y placer des Abeilles. Les abeilles sont des insectes indispensables \u00e0 la pollinisation. Ainsi une plantation sans Abeilles ne donnera pas ou peu de l\u00e9gumes, fruits ou graines. On estime en effet que 80% des plantes, arbres et fleurs sont pollinis\u00e9es par les Abeilles. Ces insectes sont donc le garant du contenu de nos assiettes. On pense qu&rsquo;il y a environ 5500 ans l&rsquo;homme \u00e0 commenc\u00e9 \u00e0 s&rsquo;organiser et \u00e0 cr\u00e9er des ruches et \u00e0 rapprocher les Abeilles de ses lieux d&rsquo;habitation. Alveola est donc un jeu qui fait du bien \u00e0 la plan\u00e8te !<\/p>\n\n\n\n<p>Un nouvel essaimage est arriv\u00e9! Prenez votre envol avec votre colonie et participez \u00e0 la construction d&rsquo;une nouvelle ruche. Choisissez judicieusement les tuiles que vous allez placer afin de poser vos ouvri\u00e8res et de r\u00e9colter un maximum de miel. \u00c9levez la ruche vers les sommets afin que votre reine en prenne le contr\u00f4le.&nbsp; Mais prenez garde aux frelons qui r\u00f4dent en qu\u00eate de nourriture !<\/p>\n\n\n\n<p>A son&nbsp; tour&nbsp; chaque joueur peut effectuer 4 actions:&nbsp;<\/p>\n\n\n\n<p>-activer un pouvoir de fleur, c&rsquo;est optionnel mais tr\u00e8s int\u00e9ressant comme par exemple r\u00e9cup\u00e9rer une abeille qui s&rsquo;est fait mang\u00e9e par un frelon.&nbsp;<\/p>\n\n\n\n<p>-agrandir ou \u00e9lever la ruche: le joueur commence par s\u00e9lectionner une des 3 piles qui suivent la cuill\u00e8re \u00e0 miel et prend la tuile du dessus (oui, comme dans Patchwork!). Il d\u00e9place ensuite la cuill\u00e8re apr\u00e8s la pile qu&rsquo;il a s\u00e9lectionn\u00e9 et joue sa tuile. Pour agrandir la ruche, il pose simplement la tuile au sol, adjacente \u00e0 une autre tuile par au moins deux alv\u00e9oles. Le joueur re\u00e7oit alors deux jetons fleur.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Pour \u00e9lever la ruche, le joueur pose sa tuile au-dessus des tuiles d\u00e9j\u00e0 pr\u00e9sentes dans la ruche. Les alv\u00e9oles vides ( les brunes) doivent couvrir les alv\u00e9oles pleines (les jaunes) et vice-versa.&nbsp; La tuile plac\u00e9e ne peut pas \u00e9craser une abeille, une reine, ou un&nbsp; frelon. Pour chaque alv\u00e9ole que le joueur aura vide, il recevra un jeton&nbsp; miel, soit un point de victoire.<\/p>\n\n\n\n<p>&#8211; placer ou d\u00e9placer une abeille: le joueur peut placer ou d\u00e9placer une et une seule abeille sur la tuile qu&rsquo;il vient de poser et uniquement sur une alv\u00e9ole pleine. Pour placer la reine, il faut avoir pos\u00e9s 4 ouvri\u00e8res et que la reine soit au niveau 4.<\/p>\n\n\n\n<p>&#8211; d\u00e9placer un frelon: si le joueur a jou\u00e9 une tuile comportant une ic\u00f4ne frelon ou si la cuill\u00e8re \u00e0 miel \u00e0 d\u00e9pass\u00e9 la tuile frelon lors de l&rsquo;\u00e9tape de s\u00e9lection, le joueur obtient un ou plusieurs d\u00e9placements de frelon. Le frelon doit \u00eatre d\u00e9plac\u00e9 vers une alveole adjacente et peut changer de niveau. Par contre il ne peut pas aller sur la m\u00eame tuile qu&rsquo;une reine ou un autre frelon. S&rsquo;il se d\u00e9place sur une tuile avec une ouvri\u00e8re, celle-ci&nbsp; est retir\u00e9e de la partie. Cette ouvri\u00e8re pourra \u00e9ventuellement \u00eatre r\u00e9cup\u00e9r\u00e9e gr\u00e2ce \u00e0 un des pouvoirs de fleur.<\/p>\n\n\n\n<p>La fin de partie est d\u00e9clench\u00e9e d\u00e8s qu&rsquo;un joueur pose sa reine (obligatoirement sur une tuile de niveau 4). Les autres joueurs finissent leur tour mais ne peuvent plus poser leur reine.<\/p>\n\n\n\n<p>On passe alors au d\u00e9compte avec un point par jeton miel, un point pour une abeille au niveau 1, 2 points pour une abeille au niveau 2 etc&#8230;jusqu&rsquo;au niveau 4 avec 4 points. Le joueur avec le plus de points remporte la partie.<\/p>\n\n\n\n<p>A noter que le jeu peut aussi se jouer en mode \u00e9quipe.&nbsp;<\/p>\n\n\n\n<p>Vous l&rsquo;avez compris, outre les ressemblances avec Patchwork, il y a aussi un peu de Taluva dans ce jeu.<\/p>\n\n\n\n<p>Pour moi qui suis habituellement fan de gros jeux de gestion, j&rsquo;avoue qu&rsquo;Alveola \u00e0 \u00e9t\u00e9 une bonne surprise. Pass\u00e9 le c\u00f4t\u00e9 un peu enfantin des illustrations, j&rsquo;ai d\u00e9couvert un tr\u00e8s bon jeu certes familial mais f\u00e9d\u00e9rateur. Le r\u00e8gles sont simples mais le jeu offre une belle profondeur strat\u00e9gique.&nbsp; Il faut optimiser au maximum le placement de ses tuiles et ne pas h\u00e9siter \u00e0 utiliser le frelon pour se d\u00e9barrasser des abeilles adverses. L&rsquo;interaction&nbsp; est donc au rendez-vous. Le travail d&rsquo;\u00e9dition est superbe, les tuiles son bien \u00e9paisses, les pions en bois trop mignons, bref que du bon. Enfin, je dirais que dans le monde actuel du jeu de soci\u00e9t\u00e9, il est tr\u00e8s plaisant de voir un nouvel \u00e9diteur s&rsquo;\u00e9panouir et nous offrir de nouvelles exp\u00e9riences ludiques. Longue vie \u00e0 Two Manta et \u00e0 bient\u00f4t avec mon avis sur leur nouveau jeu Stickers.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1.jpg\" alt=\"\" class=\"wp-image-59358\" style=\"width:405px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1-768x768.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/alveola-la-cite-des-abeilles-1-320x320.jpg 320w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Alveola est le tout premier jeu d&rsquo;une nouvelle maison d&rsquo;\u00e9dition cr\u00e9\u00e9e il y a deux ans Two Manta. Ils ont depuis sorti deux autres jeux: Spring Festival et le tout r\u00e9cent&nbsp;Stickers. Thomas Favreliere, l&rsquo;auteur en est aussi \u00e0 son premier essai. Et c&rsquo;est r\u00e9ussi,&nbsp; le jeu a en&#46;&#46;&#46;<\/p>\n","protected":false},"author":5,"featured_media":59356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-59355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-2022-fr","auteurs-thomas-favreliere","editeurs-two-manta","illustrateurs-matthieu-martin"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=59355"}],"version-history":[{"count":3,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59355\/revisions"}],"predecessor-version":[{"id":59640,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59355\/revisions\/59640"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/59356"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=59355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=59355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=59355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}