{"id":59859,"date":"2025-04-03T17:08:52","date_gmt":"2025-04-03T15:08:52","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=59859"},"modified":"2026-01-25T18:16:15","modified_gmt":"2026-01-25T17:16:15","slug":"minos-laube-de-lage-du-bronze","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2025\/04\/03\/minos-laube-de-lage-du-bronze\/","title":{"rendered":"Minos: L&rsquo;Aube de l&rsquo;Age du Bronze"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"372\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze.jpg\" alt=\"\" class=\"wp-image-61733\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze.jpg 372w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/4071-minos-l-aube-de-l-age-de-bronze-320x320.jpg 320w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-1024x768.jpg\" alt=\"\" class=\"wp-image-58881\" style=\"width:106px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-327x245.jpg 327w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73-453x340.jpg 453w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/09\/Swa-73.jpg 1089w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">SwatSh&nbsp;<\/mark>: <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">7,5\/10<\/mark><\/h5>\n\n\n\n<p>On ne raterait pour rien au monde la sortie experte annuelle de <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/editeurs\/boarddice\/\">Board &amp; Dice<\/a><\/strong> (<strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2023\/11\/03\/nucleum\/\">Nucleum<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2024\/10\/27\/vin-djeu-dlannee-2024\/\">Vin d\u2019jeu d\u2019coup d\u2019c\u0153ur 2024<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2024\/11\/03\/windmill-valley\/\">Windmill Valley<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2023\/09\/25\/barcelona\/\">Barcelona<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2022\/11\/15\/tiletum\/\">Tiletum<\/a><\/strong>,\u2026) au salon d\u2019Essen.&nbsp; Cette ann\u00e9e, c\u2019\u00e9tait Minos L&rsquo;AUbe de l&rsquo;Age du Bronze qui \u00e9tait mis \u00e0 l\u2019honneur et qui, comme la majorit\u00e9 de leurs titres, se voit aujourd&rsquo;hui traduit en Fran\u00e7ais par <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/editeurs\/pixie-games\/\">Pixie Games<\/a><\/strong>!<\/p>\n\n\n\n<p>Minos est un <strong>eurogame<\/strong> sous couvert d\u2019un th\u00e8me de <strong>jeu de civilisation<\/strong>.&nbsp; Alors oui, on va grimper sur une \u00e9chelle d\u2019influence, sur une \u00e9chelle culturelle et sur une de population, alors oui, on va voyager sur une carte pour y placer nos soldats, y construire des cit\u00e9s, des tours et des fermes, alors oui, on va envoyer nos bateaux le long des routes commerciales, mais avouons-le, le th\u00e8me est plus anecdotique ici que dans n\u2019importe quel autre jeu de civilisation.&nbsp; Dans Minos, on va tenter d\u2019atteindre les objectifs de partie avant ses adversaires, on va tenter d\u2019optimiser et de combiner au mieux les effets court et long terme de nos cartes, on va g\u00e9rer nos ressources, augmenter notre capacit\u00e9 de production, planifier l\u2019ordre de nos actions et gagner les bonus de toutes nos actions.&nbsp; On va faire tout \u00e7a, oui, mais pas vraiment faire \u00e9voluer une civilisation pour la mener \u00e0 la victoire\u2026<\/p>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-2-1024x768.jpg\" alt=\"\" class=\"wp-image-59862\" style=\"width:809px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-2.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Le c\u0153ur du jeu est <strong>un syst\u00e8me de draft de d\u00e9<\/strong> comme on a pu le rencontrer dans le tr\u00e8s bon <a href=\"https:\/\/www.vindjeu.eu\/prd\/2019\/10\/24\/rurik-dawn-of-kiev\/\"><strong>Rurik<\/strong> <\/a>(normal, c\u2019est <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/stan-kordonskiy\/\">le m\u00eame auteur<\/a><\/strong>&nbsp;\ud83d\ude0a).&nbsp; Apr\u00e8s que les d\u00e9s soient jet\u00e9s, les joueurs vont, chacun \u00e0 leur tour, choisir un des d\u00e9s disponibles et le placer, sur un socle de sa couleur, sur une case action disponible.&nbsp; Il y a 5 actions possibles dans Minos et la valeur du d\u00e9 va indiquer sur quelle case exactement vous allez pouvoir placer le d\u00e9.&nbsp; De plus, la couleur du d\u00e9 importe car si vous s\u00e9lectionnez plusieurs d\u00e9s d\u2019une m\u00eame couleur vous pourrez progresser sur l\u2019\u00e9chelle de m\u00eame couleur et r\u00e9colter ses bonus.&nbsp; Enfin, l\u2019ordre de r\u00e9alisation de vos actions d\u00e9pend de la valeur des d\u00e9s choisis.&nbsp; Vous r\u00e9aliserez vos action du d\u00e9 de valeur la plus \u00e9lev\u00e9e au d\u00e9 le plu faible. &nbsp;Cette phase est savoureuse car les choix impliquent tellement de choses qu\u2019ils sont \u00e0 chaque fois difficiles.&nbsp; Il faudra donc bien choisir son d\u00e9 en fonction de sa valeur, de sa couleur, de l\u2019ordre que vous voulez suivre pour r\u00e9aliser les actions et de la case action qu\u2019on vise \u00e0 occuper \u00e0 la fin de cette phase (la place d\u2019action de vos d\u00e9 peut bouger en fonction des choix des adversaires car les d\u00e9s sont class\u00e9s par valeur croissante).&nbsp; Tout \u00e7a donne du suspense, une certaine prise de risque, des coups fourr\u00e9s et une belle interaction.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-7-1024x768.jpg\" alt=\"\" class=\"wp-image-59863\" style=\"width:516px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-7-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-7-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-7-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-7.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<p>Le reste du jeu est plus classique dans le monde des eurogames experts avec principalement de nombreux bonus \u00e0 d\u00e9clencher un peu partout \u00e0 chaque action qu\u2019on va r\u00e9aliser.&nbsp; Minos sort un peu du lot ici en proposant <strong>de nombreux d\u00e9clenchements en chaine<\/strong>&nbsp;: je r\u00e9alise telle action qui, gr\u00e2ce \u00e0 mes capacit\u00e9s permanentes d\u00e9clenche tel et tel effet qui me permet de jouer une carte qui donne tel bonus et me permet de jouer tel autre carte qui me permet de monter sur telle \u00e9chelle qui me donne tel bonus,\u2026<\/p>\n\n\n\n<p>Un autre aspect qui m\u2019a beaucoup plus dans Minos Down of the Bronze Age est la gestion des ressources avec des <strong>ressources permanentes<\/strong> qu\u2019on ne perd jamais et qui donnent des r\u00e9ductions de co\u00fbt pour certaines actions et des ressources temporaires qui peuvent \u00eatre d\u00e9pens\u00e9es pour donner le m\u00eame effet ou qui peuvent \u00eatre \u00e9chang\u00e9es au prix de 3 pour 1 ressource permanente.<\/p>\n\n\n\n<p>Enfin, le dernier \u00e9l\u00e9ment savoureux est <strong>la liste des actions libres<\/strong> qu\u2019on peut faire \u00e0 son tour.&nbsp; Contrairement \u00e0 la majorit\u00e9 des autres jeux qui en proposent, les actions libres de <strong>Minos L&rsquo;Aube de l&rsquo;Age de Bronze<\/strong> sont int\u00e9ressantes et non une fa\u00e7on de vous en sortir quand m\u00eame \u00e0 un co\u00fbt tr\u00e8s \u00e9lev\u00e9.&nbsp; De telle fa\u00e7on qu\u2019on va en abuser et en r\u00e9aliser tr\u00e8s souvent, les combinant avec nos actions pour arriver \u00e0 faire des choses tr\u00e8s satisfaisantes. Contrairement au minotaure, Minos l&rsquo;Aube de l&rsquo;Age de Bronze&nbsp;\ud83d\ude0a On oublie vite son th\u00e8me pour se plonger dans ses m\u00e9canismes, dans la combinaison des nombreuses cartes, bonus et actions diff\u00e9rentes pour optimiser les PVs g\u00e9n\u00e9r\u00e9s par \u00e0 peu pr\u00e8s tout dans le jeu&nbsp;\ud83d\ude0a Mais pas n\u2019importe quels m\u00e9canismes et on se surprend \u00e0 beaucoup les appr\u00e9cier comme la m\u00e9canique de choix de d\u00e9 succulente, celle de choix d\u2019actions secondaires et celle de gestion de ressources permanentes et temporaires.&nbsp; Le tout formant un tout coh\u00e9rent, abstrait certes mais s\u2019imbriquant \u00e0 merveille\u2026 m\u00eame si ce jeu de civilisation n\u2019en comprend pas&nbsp;\ud83d\ude0a<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Nouvelles parties<\/h2>\n\n\n\n<p>Apr\u00e8s plusieurs parties de <strong>Minos<\/strong>, je diminue ma note d\u2019un point.\u00a0 Le jeu reste bien entendu tr\u00e8s tr\u00e8s bien surtout gr\u00e2ce \u00e0 la vari\u00e9t\u00e9 de ses cartes et \u00e0 l\u2019\u00e9tendue des strat\u00e9gies possibles.\u00a0 Chaque carte, chaque objectif de partie, chaque tuile capacit\u00e9 personnelle induit une strat\u00e9gie diff\u00e9rente\u00a0: plus s\u2019orienter vers les ressources, plus vers les routes maritimes, plus vers les fermes, plus vers les \u00e9chelles, plus vers les soldats, plus vers les cartes,\u2026\u00a0 Tout \u00e7a varie \u00e9norm\u00e9ment et donne l\u2019envie certaine d\u2019y rejouer.<\/p>\n\n\n\n<p>En contrepartie, Minos est trop lourd dans ses combos.&nbsp; Il est construit de sorte qu\u2019il y a une vraie mont\u00e9e en en puissance dans les combos.&nbsp; Cette mont\u00e9e en puissance est tellement forte qu\u2019\u00e0 la fin, on ne s\u2019en sort plus dans toutes ces combos.&nbsp; Chaque tour de joueur met une \u00e9ternit\u00e9 \u00e0 se r\u00e9soudre tellement chaque action a des effets&nbsp;: et va-t\u2019en que je gagne ceci, qui me permet de faire \u00e7a qui me donne \u00e7a et que j\u2019utilise ici pour faire \u00e7a, ce qui me donne ceci et qui me permet de gagner \u00e7a,\u2026&nbsp; Evidemment, quand c\u2019est \u00e0 nous \u00e0 jouer, c\u2019est tr\u00e8s gai, mais quand c\u2019est \u00e0 un adversaire de jouer, il y a tellement d\u2019effets qu\u2019on ne le suit plus et qu\u2019on attend que \u00e7a s\u2019arr\u00eate&nbsp;: \u00ab&nbsp;T\u2019as fini&nbsp;maintenant&nbsp;?&nbsp;\u00bb&nbsp;\ud83d\ude0a<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-25-1024x768.jpg\" alt=\"\" class=\"wp-image-59864\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-25-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-25-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-25-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-25.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-26-vin-1024x768.jpg\" alt=\"\" class=\"wp-image-59865\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-26-vin-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-26-vin-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-26-vin-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/11\/3965-Minos-26-vin.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Voil\u00e0 un petit vin tr\u00e8s fruit\u00e9 qui passe bien avec le design de Minos<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> On ne raterait pour rien au monde la sortie experte annuelle de Board &amp; Dice (Nucleum, Vin d\u2019jeu d\u2019coup d\u2019c\u0153ur 2024, Windmill Valley, Barcelona, Tiletum,\u2026) au salon d\u2019Essen.&nbsp; Cette ann\u00e9e, c\u2019\u00e9tait Minos L&rsquo;AUbe de l&rsquo;Age du Bronze qui \u00e9tait mis \u00e0 l\u2019honneur et qui, comme la majorit\u00e9 de&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":61733,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[],"class_list":["post-59859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","annee-4502","auteurs-stan-kordonskiy","editeurs-board-dice","editeurs-pixie-games","distributeurs-pixie-games","nombre_conseille-1550","nombre_conseille-1185","nombre_conseille-1210","mecanismes-asymetrie-construite","mecanismes-draft","mecanismes-gestion-de-main-de-cartes","mecanismes-jets-de-des","mecanismes-majorite","mecanismes-revenus"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=59859"}],"version-history":[{"count":8,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59859\/revisions"}],"predecessor-version":[{"id":65292,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/59859\/revisions\/65292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/61733"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=59859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=59859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=59859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}