{"id":60557,"date":"2025-01-19T20:18:02","date_gmt":"2025-01-19T19:18:02","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=60557"},"modified":"2025-01-20T09:24:21","modified_gmt":"2025-01-20T08:24:21","slug":"kathmandu","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2025\/01\/19\/kathmandu\/","title":{"rendered":"Kathmandu"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"900\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2.png\" alt=\"\" class=\"wp-image-60558\" style=\"width:477px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2.png 900w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2-768x768.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2-80x80.png 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-2-320x320.png 320w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/20241003_171410779_iOS-1024x768.jpg\" alt=\"\" class=\"wp-image-59245\" style=\"width:147px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/20241003_171410779_iOS-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/20241003_171410779_iOS-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/20241003_171410779_iOS-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/20241003_171410779_iOS-rotated.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">SwatSh<\/mark>&nbsp;: <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">7\/10<\/mark><\/h5>\n\n\n\n<p>Kathmandu est le dernier <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/stefan-feld\/\">Feld <\/a><\/strong>initi\u00e9 sorti par <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/editeurs\/queen-games\/\">Queen Games<\/a><\/strong> (<strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2023\/08\/26\/marrakesh-essential-edition\/\">Marrakesh<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2024\/04\/25\/cuzco-2\/3\">Cuzco<\/a><\/strong>, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2022\/10\/08\/kokopelli\/\">Kokopelli<\/a><\/strong>,\u2026).&nbsp; Contrairement \u00e0 d\u2019autres, il ne s\u2019agit pas d\u2019une r\u00e9\u00e9dition mais bien d\u2019un tout nouveau jeu du ma\u00eetre.&nbsp;<\/p>\n\n\n\n<p>Kathmandu est un jeu de course avec salade de points et dirig\u00e9 par des d\u00e9s.&nbsp; Au d\u00e9but de votre tour, vous allez jeter 6 d\u00e9s qui vont indiquer les ressources dont vous disposerez ainsi que votre capacit\u00e9 de d\u00e9placement.&nbsp; Qui dit salade de points dit diff\u00e9rentes fa\u00e7ons de scorer.&nbsp; M\u00eame si arriver premier dans la course \u00e0 Kathmandu vous procurera pas mal de points, visiter la ville, son temple, collectionner des choses, prendre des photos des animaux,\u2026 vous apporteront aussi leurs lots de PVs qu\u2019il ne faudra pas n\u00e9gliger.&nbsp; La fa\u00e7on de scorer certains \u00e9l\u00e9ments m\u2019a d\u2019ailleurs fait un peu penser \u00e0 <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2020\/01\/29\/glen-more-ii-chronicles\/\">Glen More<\/a><\/strong> o\u00f9 celle qui a r\u00e9colt\u00e9 le plus d\u2019un \u00e9l\u00e9ment score en fonction de celle qui en a r\u00e9colt\u00e9 le moins.&nbsp; Plus la diff\u00e9rence entre les 2 joueuses est grande, plus de points elle gagnera.&nbsp; Vous pourrez \u00e9galement gagner des cartes qui vont vous donner des bonus normalement impossibles comme traverser les montagnes ou faire des mouvements interdits.&nbsp;<\/p>\n\n\n\n<p>Les cartes de <strong>Kathmandu<\/strong> vont un peut rompre la rigidit\u00e9 du jeu qui vous oblige \u00e0 suivre le trac\u00e9 rectiligne du jeu et \u00e0 faire des actions peu efficaces et inint\u00e9ressantes.\u00a0 Le jeu reste tr\u00e8s classique pouvant \u00eatre r\u00e9sum\u00e9 \u00e0 un jeu de collection o\u00f9 vos choix seront guid\u00e9s par les points que vous pourrez engranger.\u00a0 Les choix les plus int\u00e9ressants se situent dans l\u2019utilisation des d\u00e9s.\u00a0 Quels d\u00e9s vont me servir \u00e0 quoi (ressources ou progression)\u00a0? \u00a0J\u2019ai bien aim\u00e9 le fait que ce n\u2019est pas n\u00e9cessairement les joueurs les plus rapides dans la course qui vont l\u2019emporter et s\u2019arr\u00eater aux bons endroits en chemin peut faire la diff\u00e9rence.\u00a0 De plus, plus vous avancerez vite, plus loin vous serez dans l\u2019ordre du tour laissant les actions les plus lucratives aux plus lents.\u00a0 La patte de <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/stefan-feld\/\">Stefan Feld<\/a><\/strong> est bien l\u00e0\u00a0\ud83d\ude0a\u00a0 Si vous \u00eates un fan de <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/stefan-feld\/\">Feld<\/a><\/strong>, ce jeu vous ravira certainement surtout si vous aimez ses jeux pour initi\u00e9s ou des jeux de course comme La Course vers El Dorado.\u00a0 Ne vous attendez cependant pas \u00e0 ce qu\u2019il vous propose autant de profondeur strat\u00e9gique ou de long\u00e9vit\u00e9 comme <a href=\"https:\/\/www.vindjeu.eu\/prd\/2021\/03\/04\/bonfire-vf\/\"><strong>Bonfire<\/strong> <\/a>ou <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2023\/08\/26\/marrakesh-essential-edition\/\">Marrakesh \u00a0<\/a><\/strong>peuvent offrir.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"675\" height=\"900\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-5.png\" alt=\"\" class=\"wp-image-60559\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-5.png 675w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/12\/4013-Kathmandu-5-225x300.png 225w\" sizes=\"auto, (max-width: 675px) 100vw, 675px\" \/><\/figure>\n<\/div>\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Kathmandu est le dernier Feld initi\u00e9 sorti par Queen Games (Marrakesh, Cuzco, Kokopelli,\u2026).&nbsp; Contrairement \u00e0 d\u2019autres, il ne s\u2019agit pas d\u2019une r\u00e9\u00e9dition mais bien d\u2019un tout nouveau jeu du ma\u00eetre.&nbsp; Kathmandu est un jeu de course avec salade de points et dirig\u00e9 par des d\u00e9s.&nbsp; Au d\u00e9but de&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":60558,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[],"class_list":["post-60557","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","annee-4502","auteurs-stefan-feld","editeurs-queen-games","illustrateurs-lukas-siegmon","illustrateurs-patricia-limberger"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=60557"}],"version-history":[{"count":2,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60557\/revisions"}],"predecessor-version":[{"id":60888,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60557\/revisions\/60888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/60558"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=60557"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=60557"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=60557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}