{"id":60907,"date":"2025-02-08T17:43:30","date_gmt":"2025-02-08T16:43:30","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=60907"},"modified":"2025-07-02T21:25:33","modified_gmt":"2025-07-02T19:25:33","slug":"stella-quest","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2025\/02\/08\/stella-quest\/","title":{"rendered":"Stella Quest"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"433\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-1.png\" alt=\"\" class=\"wp-image-60908\" style=\"width:361px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-1.png 433w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-1-217x300.png 217w\" sizes=\"auto, (max-width: 433px) 100vw, 433px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Essen-Spiel-2024-500-1024x768.jpg\" alt=\"\" class=\"wp-image-59278\" style=\"width:170px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Essen-Spiel-2024-500-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Essen-Spiel-2024-500-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Essen-Spiel-2024-500-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2024\/10\/Essen-Spiel-2024-500-rotated.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">SwatSh<\/mark>: <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> 10\/10<\/mark><\/h5>\n\n\n\n<p>Stella Quest est un jeu de plis d&rsquo;apparence tr\u00e8s classique: <strong>must follow, if not, may cut<\/strong>.  Mais le truc ici est qu&rsquo;il faut \u00eatre le premier \u00e0 avoir une carte de chacune des valeurs allant de 1 \u00e0 6.  Pour ce faire, lorsqu&rsquo;on gagne un pli, <strong>on choisit une des cartes du pli<\/strong> et on la place devant soi.  Il faut n\u00e9anmoins veiller \u00e0 ne pas prendre 2 fois la m\u00eame valeur de carte car on devra, alors, \u00e9teindre une de ses \u00e9toiles&#8230;  Evidemment, les autres se feront un malin plaisir \u00e0 vous filer les cartes que vous avez d\u00e9j\u00e0 \ud83d\ude09<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#6061af\" class=\"has-inline-color\">Stella<\/mark><\/h2>\n\n\n\n<p>La seconde m\u00e9canique tr\u00e8s sympa dans Stella Quest est son syst\u00e8me d&rsquo;\u00e9toiles.  <strong>Les joueuses commencent la partie avec 5 \u00e9toiles brillantes<\/strong> devant elles et devront, suite \u00e0 certains \u00e9v\u00e9nements (comme celui de prendre 2 fois la m\u00eame carte), les retourner face \u00e9teinte.  Quand une joueuse se retrouve avec aucune carte en main, elle en <strong>pioche <\/strong>autant qu&rsquo;elle a d&rsquo;\u00e9toiles brillantes.  Mieux vaut ne pas les bruler trop vite au risque de se retrouver trop vite avec tr\u00e8s peu de cartes en main et donc tr\u00e8s peu de choix quitte \u00e0 se retrouver, trop souvent, coinc\u00e9e&#8230;  De plus, ne plus avoir d&rsquo;\u00e9toile brillante devant soi \u00e9quivaut \u00e0 \u00eatre \u00e9limin\u00e9e de la partie.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#6061af\" class=\"has-inline-color\">Atout<\/mark><\/h2>\n\n\n\n<p>Stella Quest s\u00e9duit \u00e9galement dans sa mani\u00e8re, tr\u00e8s \u00e9l\u00e9gante, de <strong>d\u00e9terminer l&rsquo;atout<\/strong>.  Lorsqu&rsquo;on gagne un pli, on en garde une des cartes et on place les autres dans la d\u00e9fausse en choisissant leur ordre qui est loin d&rsquo;\u00eatre anodin puisque la carte du dessus de la d\u00e9fausse deviendra l&rsquo;atout.  De plus, <strong>gagner 2 plis 2 tours en suivant<\/strong> vous obligera \u00e0 \u00e9teindre une \u00e9toile.  Vous allez donc, du moins en d\u00e9but de partie, \u00e9viter \u00e0 tout prix de prendre 2 plis en suivants.  En fin de partie, par contre, pour arriver \u00e0 prendre les autres de vitesse (Stella Quest est une course) gagner plusieurs plis en suivant peut \u00eatre un choix gagnant.  Choisir un atout en fonction de votre tactique devient donc crucial surtout que, un peu comme dans l&rsquo;excellent <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2024\/01\/26\/luz\/\">Luz<\/a><\/strong>, le dos des cartes de Stella Quest indique la couleur de la carte aux autres joueurs.  Cela va vous donner une info primordiale en fonction de ce que vous voudrez obtenir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0);color:#6061af\" class=\"has-inline-color\">Stellaire<\/mark><\/h2>\n\n\n\n<p><strong>Stella Quest<\/strong> apporte un vent de fraicheur dans le monde des jeux de plis.  Il arrive \u00e0 proposer de nouvelles m\u00e9caniques tr\u00e8s \u00e9l\u00e9gantes encourageant les joueuses \u00e0 faire des choix cruciaux dans le choix des cartes composant chacun de leurs plis: quelle carte garder, quelle carte choisir pour d\u00e9terminer l&rsquo;atout,&#8230;  Tout cela dans un jeu de plis tr\u00e8s malin, m\u00e9chant, o\u00f9 vous devrez g\u00e9rer vos couleurs, l&rsquo;atout, le nombre de cartes que vous pourrez piocher tout en ayant plus d&rsquo;infos sur les cartes des autres joueuses.  Stella Quest est, une fois n&rsquo;est pas coutume,  une course tr\u00e9pignante tout en restant, dans son essence m\u00eame, un jeu de plis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Nouvelles parties<\/h2>\n\n\n\n<p>Apr\u00e8s plusieurs parties, je ne puis que maintenir ma note toppissime \ud83d\ude09  Stella Quest se d\u00e9voile petit \u00e0 petit et de nouvelles possibilit\u00e9s strat\u00e9giques peuvent encore se pr\u00e9senter.  Savez vous qu&rsquo;il peut \u00eatre int\u00e9ressant de retourner une de ses \u00e9toiles pour piocher 3 cartes?  Ca peut m\u00eame vous faire gagner!  Alors oui, Stella Quest est riche et, m\u00eame apr\u00e8s de nombreuses parties, toujours autant surprenant!<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-2-1024x768.jpg\" alt=\"\" class=\"wp-image-60909\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-2-768x576.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/01\/4041-Stella-Quest-2.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p> Stella Quest est un jeu de plis d&rsquo;apparence tr\u00e8s classique: must follow, if not, may cut. Mais le truc ici est qu&rsquo;il faut \u00eatre le premier \u00e0 avoir une carte de chacune des valeurs allant de 1 \u00e0 6. Pour ce faire, lorsqu&rsquo;on gagne un pli, on choisit&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":60908,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[],"class_list":["post-60907","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","annee-4502","auteurs-beomhee-kim","editeurs-koreaboardgames","illustrateurs-doming","nombre_conseille-1210","nombre_conseille-1355","mecanismes-jeu-de-plis"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60907","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=60907"}],"version-history":[{"count":5,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60907\/revisions"}],"predecessor-version":[{"id":62557,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/60907\/revisions\/62557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/60908"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=60907"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=60907"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=60907"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}