{"id":61658,"date":"2025-04-08T19:37:21","date_gmt":"2025-04-08T17:37:21","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=61658"},"modified":"2025-04-08T19:37:21","modified_gmt":"2025-04-08T17:37:21","slug":"balconia","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2025\/04\/08\/balconia\/","title":{"rendered":"Balconia"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia.jpg\" alt=\"\" class=\"wp-image-61659\" style=\"width:485px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-320x320.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"576\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-576x1024.jpeg\" alt=\"\" class=\"wp-image-61660\" style=\"width:94px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-576x1024.jpeg 576w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-169x300.jpeg 169w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-768x1365.jpeg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-864x1536.jpeg 864w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-1152x2048.jpeg 1152w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/IMG-20240810-WA0005-1-7-scaled.jpeg 1440w\" sizes=\"auto, (max-width: 576px) 100vw, 576px\" \/><\/figure>\n<\/div>\n\n\n<h4 class=\"wp-block-heading has-vivid-cyan-blue-color has-text-color has-link-color wp-elements-254cc14540f5281e0726f7e25ea9de9d\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">Mart<\/mark>i<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">ne:<\/mark> <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\">8\/10<\/mark><\/h4>\n\n\n\n<p>Balconia est un jeu pour 2 joueurs \u00e9dit\u00e9 chez Origames, cr\u00e9\u00e9 par Paul Schultz et illustr\u00e9 par Natalya Efremova. La vie en immeuble est souvent anim\u00e9e. Certains prennent des cours de musique et ne sont pas tr\u00e8s dou\u00e9s et par cons\u00e9quent cassent les oreilles de leurs voisins.&nbsp; D&rsquo;autres recueillent tous les chats errants du voisinage. Certains amoureux transis se prennent pour Rom\u00e9o et Juliette et d\u00e9clarent leur flamme d&rsquo;un balcon \u00e0 l&rsquo;autre. Mais dans Balconia, vous allez devoir faire cohabiter tout ce petit monde le plus harmonieusement possible. Construisez bloc par bloc un immeuble. Pour marquer des points, optimisez le placement des balcons de votre c\u00f4t\u00e9 de l&rsquo;immeuble tout en \u00e9vitant de favoriser celui de votre adversaire.&nbsp;<\/p>\n\n\n\n<p>Balconia est un jeu en 3D et quand j&rsquo;ai vu la structure de l&rsquo;immeuble je n&rsquo;ai pas pu m&#8217;emp\u00eacher de penser \u00e0 puissance 4 ( oui, je suis assez vieille pour y avoir jou\u00e9 quand j&rsquo;\u00e9tais petite)<\/p>\n\n\n\n<p>Tr\u00eave de plaisanterie, comment on joue \u00e0 Balconia?<\/p>\n\n\n\n<p>Placez la grille entre les deux adversaires assis face \u00e0 face. S\u00e9lectionnez au hasard un bloc porte d&rsquo;entr\u00e9e (int\u00e9rieur rose). La couleur de la porte qui vous fait face, rose ou turquoise sera votre couleur pour la partie. Placez les 22 jetons face cach\u00e9e sur la table, prenez en 8 que vous remettrez dans la boite.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"600\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1.jpg\" alt=\"\" class=\"wp-image-61661\" style=\"width:468px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1.jpg 600w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1-80x80.jpg 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/balconia-1-320x320.jpg 320w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n\n\n<p>Chaque tour, l&rsquo;un de vous s\u00e9lectionne un bloc balcon et l&rsquo;autre le place dans l&rsquo;immeuble. La personne turquoise commence la partie. Elle r\u00e9v\u00e8le l&rsquo;un des jetons face cach\u00e9e,&nbsp; puis prend le bloc balcon correspondant. La personne turquoise regarde ensuite chaque face du bloc, en choisit 2 adjacentes et place le bloc sur le disque de s\u00e9lection en veillant \u00e0 mettre les 2 faces choisies de son c\u00f4t\u00e9 du disque, sur la couleur turquoise.&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-768x1024.jpg\" alt=\"\" class=\"wp-image-61708\" style=\"width:414px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-1152x1536.jpg 1152w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-1536x2048.jpg 1536w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/03\/20250329_093157-scaled.jpg 1920w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n<p>La personne rose prend le disque de s\u00e9lection avec le bloc. Elle peut consulter les 4 faces du bloc mais seules deux d&rsquo;entre elles lui sont disponibles.&nbsp; Puis la personne rose choisit une des deux faces et place le bloc dans l&rsquo;immeuble.&nbsp;<\/p>\n\n\n\n<p>Le tour prend fin et vous \u00e9changez les r\u00f4les.&nbsp; Chaque nouveau balcon doit \u00eatre adjacent \u00e0 un balcon plac\u00e9 pr\u00e9c\u00e9demment.&nbsp;<\/p>\n\n\n\n<p>La m\u00e9canique centrale de \u00ab\u00a0i Split you choose\u00a0\u00bb est tr\u00e8s efficace et il y a forc\u00e9ment beaucoup d&rsquo;int\u00e9raction. Au niveau du scoring, cela fait un peu pense \u00e0 Ch\u00e2teau Combo.<\/p>\n\n\n\n<p>Le mat\u00e9riel est tr\u00e8s bien con\u00e7u mais r\u00e9sistera-t&rsquo;il sur le long terme ? Pas sur. Les blocs d&rsquo;immeubles sont un peu fragiles.<\/p>\n\n\n\n<p>C\u00f4t\u00e9 illustrations,&nbsp; c&rsquo;est tr\u00e8s frais et plut\u00f4t amusant. Une belle d\u00e9couverte ludique.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Balconia est un jeu pour 2 joueurs \u00e9dit\u00e9 chez Origames, cr\u00e9\u00e9 par Paul Schultz et illustr\u00e9 par Natalya Efremova. La vie en immeuble est souvent anim\u00e9e. Certains prennent des cours de musique et ne sont pas tr\u00e8s dou\u00e9s et par cons\u00e9quent cassent les oreilles de leurs voisins.&nbsp; D&rsquo;autres&#46;&#46;&#46;<\/p>\n","protected":false},"author":5,"featured_media":61659,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[],"class_list":["post-61658","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","annee-4502","auteurs-paul-schultz","editeurs-origames","illustrateurs-natalya-efremova","mecanismes-abstrait"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/61658","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=61658"}],"version-history":[{"count":5,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/61658\/revisions"}],"predecessor-version":[{"id":61759,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/61658\/revisions\/61759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/61659"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=61658"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=61658"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=61658"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}