{"id":64322,"date":"2025-11-21T14:26:30","date_gmt":"2025-11-21T13:26:30","guid":{"rendered":"https:\/\/www.vindjeu.eu\/prd\/?p=64322"},"modified":"2025-11-21T14:26:30","modified_gmt":"2025-11-21T13:26:30","slug":"fantasy-brewers","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2025\/11\/21\/fantasy-brewers\/","title":{"rendered":"Fantasy Brewers"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-1024x1024.png\" alt=\"\" class=\"wp-image-64323\" style=\"width:485px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-1024x1024.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-300x300.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-150x150.png 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-768x768.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-80x80.png 80w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1-320x320.png 320w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-1.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"691\" height=\"724\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/Swa-77-Natera.jpg\" alt=\"\" class=\"wp-image-63854\" style=\"width:147px;height:auto\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/Swa-77-Natera.jpg 691w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/10\/Swa-77-Natera-286x300.jpg 286w\" sizes=\"auto, (max-width: 691px) 100vw, 691px\" \/><\/figure>\n<\/div>\n\n\n<h5 class=\"wp-block-heading\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-cyan-blue-color\">SwatSh<\/mark>: <mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-vivid-red-color\"> 7\/10<\/mark><\/h5>\n\n\n\n<p>Fantasy Brewers est le dernier jeu de <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/michael-schacht\/\">Michael Schacht<\/a><\/strong> qu&rsquo;on ne pr\u00e9sente plus vu qu&rsquo;il fait des jeux depuis plus de 30 ans!  Son premier jeu connu \u00e9tait Kardinaal &amp; Konig, sorti en 2000.  Ses plus connus sont Coloretto, <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2010\/08\/31\/hansa\/\">Hansa <\/a><\/strong>et <strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/2010\/08\/22\/zooloretto\/\">Zooloretto<\/a><\/strong>.<\/p>\n\n\n\n<p>Dans Fantasy Brewers, nous allons cr\u00e9er notre propre brasserie en engageant des brasseurs dans un monde fantastique.  <\/p>\n\n\n\n<p>Il s&rsquo;agit d&rsquo;un jeu de <strong>pose d&rsquo;ouvriers<\/strong> avec un twist sympa: <strong>la file d&rsquo;attente<\/strong>!  Chacun \u00e0 son tour va placer un ouvrier en face d&rsquo;une des portes.  Quand vous placez un ouvrier sur une des 3 portes o\u00f9 un autre ouvrier s&rsquo;y trouve d\u00e9j\u00e0, vous le placez en dessous de l&rsquo;ouvrier existant afin de former une queue.  Vous avez des plus grands ouvriers qui, quand ils sont plac\u00e9s, prot\u00e8gent les autres plus petits plac\u00e9s dans la file avant eux.  En \u00e9change des cette protection, ils devront payer une pi\u00e8ce au joueur poss\u00e9dant le plus grand ouvrier.  Si un joueur ne veut pas payer, son ouvrier r\u00e9trograde alors dans la file d&rsquo;attente et se place derri\u00e8re le dernier ouvrier.  La m\u00e9canique de file d&rsquo;attente payante est assez g\u00e9niale car vous ne savez jamais \u00e0 l&rsquo;avance si vous allez pouvoir rester \u00e0 la premi\u00e8re place d&rsquo;une file.  Cela pourrait vous co\u00fbter tr\u00e8s cher.  Mieux vaut alors placer son gros ouvrier rapidement pour s&rsquo;assurer la premi\u00e8re place mais alors il ne forcera plus vos adversaires \u00e0 vous payer&#8230;  C&rsquo;est une sorte d&rsquo;ench\u00e8re \u00e0 l&rsquo;envers, un truc bien original et tr\u00e8s interactif.  Et quand vous voyez un joueur toujours payer les gros ouvriers pour garder sa premi\u00e8re place, vous allez y placer gros ouvrier juste pour l&rsquo;obliger \u00e0 vous payer encore une pi\u00e8ce suppl\u00e9mentaire.  C&rsquo;est tr\u00e8s malin.<\/p>\n\n\n\n<p>Le reste de Fantasy Brewers est plus classique.  Apr\u00e8s que les files aient \u00e9t\u00e9 constitu\u00e9es,  chaque joueuse, dans l&rsquo;ordre de la file, va <strong>placer son ouvri\u00e8re<\/strong> sur un des emplacements d&rsquo;action libres disponibles \u00e0 partir de la porte et r\u00e9aliser l&rsquo;action correspondante.  Les action permettront de gagner des ressources, d&rsquo;\u00e9changer des ressources, de vendre des ressources, d&#8217;embaucher des cartes brasseurs,&#8230;  Les brasseurs vont fournir des ressources n\u00e9cessaires pour en gagner d&rsquo;autres en se retournant sur le face cach\u00e9e.  Il faudra alors r\u00e9aliser une action permettant de retourner \u00e0 nouveau un brasseur pour pouvoir b\u00e9n\u00e9ficier, \u00e0 nouveau, de sa ressource.<\/p>\n\n\n\n<p>M\u00eame si Fantasy Brewers est un peu r\u00e9p\u00e9titif, Michael Schacht a ajout\u00e9 un \u00e9l\u00e9ment de <strong>variabilit\u00e9 <\/strong>dans les actions \u00e0 r\u00e9aliser.  A chaque manche, une des trois portes voit les actions qu&rsquo;elle propose changer.  C&rsquo;est assez sympa.<\/p>\n\n\n\n<p>On va \u00e9galement pouvoir obtenir des <strong>extensions <\/strong>qui apportent des bonus permanents qui s&rsquo;enclenchent lorsqu&rsquo;on r\u00e9alise l&rsquo;action correspondante.  D&rsquo;autres cartes vous apporteront des PVs conditionnels de fin de partie.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.vindjeu.eu\/prd\/auteurs\/michael-schacht\/\">Michael Schacht<\/a><\/strong> est un grand auteur et il le prouve une nouvelle fois avec <strong>Fantasy Brewers<\/strong>.  La m\u00e9canique de file d&rsquo;attente payante pour \u00eatre dans les premiers \u00e0 choisir une action est tr\u00e8s originale et marche du tonnerre.  Elle offre beaucoup d&rsquo;interactions et \u00e7a fait du bien dans la production actuelle qui n&rsquo;en propose que trop peu.  Le jeu offre une jolie variabilit\u00e9 m\u00eame si, en soi, on va passer beaucoup temps \u00e0 gagner, \u00e9changer et vendre des ressources.  Les cartes capacit\u00e9s et objectifs personnels vont apporter des axes strat\u00e9giques int\u00e9ressants.  Je conseille ce jeu \u00e0 partir de 3 joueurs car \u00e0 2, le nombre de cases action reste le m\u00eame offrant moins de tension au jeu.  Apr\u00e8s une partie de Fantasy Brewers, on n&rsquo;a qu&rsquo;une seule envie, d\u00e9guster un bon petit verre de vin \ud83d\ude42<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<p><\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<figure class=\"wp-block-image alignfull size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"577\" src=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-5-1024x577.png\" alt=\"\" class=\"wp-image-64324\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-5-1024x577.png 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-5-300x169.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-5-768x433.png 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2025\/11\/4216-Fantasy-Brewers-5.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Fantasy Brewers est le dernier jeu de Michael Schacht qu&rsquo;on ne pr\u00e9sente plus vu qu&rsquo;il fait des jeux depuis plus de 30 ans! Son premier jeu connu \u00e9tait Kardinaal &amp; Konig, sorti en 2000. Ses plus connus sont Coloretto, Hansa et Zooloretto. Dans Fantasy Brewers, nous allons cr\u00e9er&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":64323,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[],"class_list":["post-64322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","annee-4745","auteurs-michael-schacht","editeurs-grail-games","illustrateurs-matthew-sellers","nombre_conseille-1210","nombre_conseille-1355"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/64322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=64322"}],"version-history":[{"count":8,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/64322\/revisions"}],"predecessor-version":[{"id":64407,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/64322\/revisions\/64407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/64323"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=64322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=64322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=64322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}