{"id":6504,"date":"2014-01-05T19:26:18","date_gmt":"2014-01-05T18:26:18","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=6504"},"modified":"2014-01-05T19:26:18","modified_gmt":"2014-01-05T18:26:18","slug":"continental-express","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/01\/05\/continental-express\/","title":{"rendered":"Continental Express"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6506\" title=\"678 Continental express 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1.png\" alt=\"\" width=\"309\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1.png 441w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1-264x300.png 264w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1-132x150.png 132w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-1-400x453.png 400w\" sizes=\"auto, (max-width: 309px) 100vw, 309px\" \/><\/a><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0<strong><span style=\"color: #800000;\">\u00a0\u00a07\/10<\/span><\/strong><\/p>\n<p>Continental Express est un petit jeu de cartes sans pr\u00e9tention qui reprend des syt\u00e8mes de jeux plut\u00f4t orient\u00e9s \u00ab\u00a0joueurs\u00a0\u00bb pour les adapter \u00e0 un mode plus familial.\u00a0 Son auteur, Charles Chevallier, est loin d&rsquo;\u00eatre un inconnu puisqu&rsquo;il a d\u00e9j\u00e0 r\u00e9alis\u00e9 d&rsquo;autres tr\u00e8s bons jeux familiaux tels que <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/04\/04\/gentlemen-cambrioleurs\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Gentlemen Cambrioleurs <\/span><\/a><\/span>et <a href=\"http:\/\/www.vindjeu.eu\/2011\/02\/20\/le-secret-de-monte-cristo\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Le Secret de Monte Cristo<\/span><\/a>.<\/p>\n<p>Les joueurs d\u00e9butent la partie avec un contrat qui leur donnera des PVs suppl\u00e9mentaires \u00e0 la fin de la partie.\u00a0 Le tout est de deviner les contrats adverses pour leur couper l&rsquo;herbe sous le pied \ud83d\ude09<\/p>\n<p>A son tour de jeu, un joueur prend une des 9 cartes wagon expos\u00e9es et paye son prix en fonction de sa place dans la rang\u00e9e.\u00a0 L&rsquo;argent est distribu\u00e9 au d\u00e9but de la partie et on ne sait pas en gagner ensuite, il va donc falloir faire avec \ud83d\ude42\u00a0 Ensuite, le joueurpeut valider un objectif si une combinaison de ses cartes wagons donne la combinaison exig\u00e9e par une des 3 cartes objectif visibles sur la table.\u00a0 S&rsquo;il le fait, il prend la carte objectif et l&rsquo;ajoute \u00e0 son train.\u00a0 Cette carte lui donnera des PVs mais aussi des PVs suppl\u00e9mentaires si elle correspond aux exigences de son contrat.<\/p>\n<p>Ajouter \u00e0 \u00e7a quelques cartes sp\u00e9ciales \u00e0 piocher, les personnages, qui donnent un bonus imm\u00e9diat (piocher une carte suppl\u00e9mentaire gratuitement, prendre les billets d&rsquo;un autre joueur, \u00e9changer un wagon avec un wagon adverse,&#8230;) et vous obtenez un petit jeu bien sympa \u00e0 jouer en famille sans se prendre la t\u00eate \ud83d\ude09<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6505\" title=\"678 Continental express 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2.jpg\" alt=\"\" width=\"478\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2.jpg 478w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2-286x300.jpg 286w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2-143x150.jpg 143w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/11\/678-Continental-express-2-400x418.jpg 400w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Continental Express est un petit jeu de cartes sans pr\u00e9tention qui reprend des syt\u00e8mes de jeux plut\u00f4t orient\u00e9s \u00ab\u00a0joueurs\u00a0\u00bb pour les adapter \u00e0 un mode plus familial.\u00a0 Son auteur, Charles Chevallier, est loin d&rsquo;\u00eatre un inconnu puisqu&rsquo;il a d\u00e9j\u00e0 r\u00e9alis\u00e9 d&rsquo;autres tr\u00e8s bons jeux familiaux tels que Gentlemen Cambrioleurs&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":6506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-6504","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-549","auteurs-charles-chevallier","editeurs-bombyx"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6504","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=6504"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6504\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/6506"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=6504"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=6504"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=6504"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}