{"id":6863,"date":"2013-12-31T12:15:26","date_gmt":"2013-12-31T11:15:26","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=6863"},"modified":"2013-12-31T12:15:26","modified_gmt":"2013-12-31T11:15:26","slug":"bioutifoul","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2013\/12\/31\/bioutifoul\/","title":{"rendered":"Bioutifoul"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/bioutifoul_box1.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6865\" style=\"margin: 5px;\" title=\"bioutifoul_box\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/bioutifoul_box1.jpeg\" alt=\"\" width=\"211\" height=\"298\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/bioutifoul_box1-213x300.jpeg 213w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/bioutifoul_box1-106x150.jpeg 106w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #0000ff;\">Philrey212:<\/span> <span style=\"color: #800000;\">7,5\/10<\/span><\/strong><\/p>\n<p>Et bien, cela fait bien longtemps que je dois faire cette petite critique mais les choses se sont un peu trop bouscul\u00e9es pour moi ces derniers temps. Aujourd&rsquo;hui, je prends enfin le temps n\u00e9cessaire pour vous faire d\u00e9couvrir, si ce n&rsquo;est d\u00e9j\u00e0 fait, ce petit jeu de cartes qui est moins simple qu&rsquo;il peut para\u00eetre.<br \/>\nBioutifoul (j&rsquo;ai de la mis\u00e8re \u00e0 l&rsquo;\u00e9crire \ud83d\ude09 est donc un jeu de carte pour jeunes et moins jeunes. L&rsquo;objectif est de faire des expositions d&rsquo;oeuvres d&rsquo;art afin de r\u00e9colter plus de points que ses adversaires.<br \/>\nAlors, cela para\u00eet simple mais pas tout \u00e0 fait. On a dans Bioutifoul un peu une m\u00e9canique de jeux plus costauds o\u00f9 il faut plusieurs \u00e9tapes pour arriver \u00e0 ses fins. Ici, pour parvenir \u00e0 faire une exposition, il faut &#8230; des oeuvres d&rsquo;art. Bon, il faudra donc les acheter ces oeuvres. Evidemment, le co\u00fbt d&rsquo;une oeuvre d\u00e9pend de la renomm\u00e9e de son artiste. Renomm\u00e9e, qu&rsquo;on pourra heureusement influencer pour ne pas se ruiner.<\/p>\n<p>Un tour de jeu est donc comme suit:<br \/>\n1) le joueur joue 1 \u00e0 3 cartes Influence pour ainsi faire modifier le prix des oeuvres. Evidemment, on ne peut influencer qu&rsquo;un seul artiste \u00e0 la fois. Petite astuce, les cartes jou\u00e9es ne sont pas d\u00e9fauss\u00e9es (comme d&rsquo;habitude) mais bien pass\u00e9es au joueur de droite.<br \/>\n2) on peut faire de 0 \u00e0 3 actions. Si on d\u00e9cide de ne pas en faire, on prend une carte lingot + une carte influence en compensation. Les actions possibles sont: acheter une oeuvre, vendre une oeuvre ou monter une exposition. Toutes les cartes sont visibles au milieu des joueurs: oeuvres disponibles (avec le nom de l&rsquo;artiste), expositions possibles (avec 2 artistes \u00e0 chaque fois).<br \/>\n3) On passe \u00e0 la banque pour recevoir une carte lingot (histoire de ne jamais se retrouver \u00ab\u00a0\u00e0 sec\u00a0\u00bb, c\u00e0d bloqu\u00e9)<\/p>\n<p>On devra donc, si vous avez bien suivi, faire modifier le prix des oeuvres, acheter des oeuvres afin de faire des expositions disponibles. En trois temps donc \ud83d\ude09<\/p>\n<p>A deux, le jeu tourne \u00e0 merveille car il est plus ais\u00e9 de contr\u00f4ler la renomm\u00e9e des artistes. A plus, c&rsquo;est d\u00e9j\u00e0 moins facile. Les graphismes sont simples, color\u00e9s et clairs, les r\u00e8gles bien \u00e9crites avec des exemples et une partie est pli\u00e9e en 30 minutes. Bref, petite bo\u00eete facile \u00e0 emmener, vite sortie pour passer une demi-heure pleine de couleurs.<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6866\" title=\"Bioutifoul en cours de partie\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970.jpg\" alt=\"\" width=\"672\" height=\"896\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970.jpg 672w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970-224x300.jpg 224w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970-112x150.jpg 112w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010970-400x533.jpg 400w\" sizes=\"auto, (max-width: 672px) 100vw, 672px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-6867\" title=\"Bioutifoul: d\u00e9dicace de Sophie Gerl\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971.jpg\" alt=\"\" width=\"539\" height=\"693\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971.jpg 539w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971-233x300.jpg 233w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971-116x150.jpg 116w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/P1010971-400x514.jpg 400w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Je vous laisse admirer la petite d\u00e9dicace de l&rsquo;illustrateur lui-m\u00eame (enfin, elle-m\u00eame ;). De toute beaut\u00e9, comme celles sur les cartes!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Et bien, cela fait bien longtemps que je dois faire cette petite critique mais les choses se sont un peu trop bouscul\u00e9es pour moi ces derniers temps. Aujourd&rsquo;hui, je prends enfin le temps n\u00e9cessaire pour vous faire d\u00e9couvrir, si ce n&rsquo;est d\u00e9j\u00e0 fait, ce petit jeu de cartes&#46;&#46;&#46;<\/p>\n","protected":false},"author":1,"featured_media":6865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6],"class_list":["post-6863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","annee-549","auteurs-pascal-notredame","editeurs-petit-joueur"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=6863"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/6865"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=6863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=6863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=6863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}