{"id":6888,"date":"2014-03-13T22:02:09","date_gmt":"2014-03-13T21:02:09","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=6888"},"modified":"2014-03-13T22:02:09","modified_gmt":"2014-03-13T21:02:09","slug":"colonial-europes-empires-overseas","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/03\/13\/colonial-europes-empires-overseas\/","title":{"rendered":"Colonial: Europe&rsquo;s Empires Overseas"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-6890\" style=\"margin: 5px;\" title=\"707 Colonial 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-1.jpg\" alt=\"\" width=\"358\" height=\"500\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-1.jpg 358w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-1-214x300.jpg 214w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-1-107x150.jpg 107w\" sizes=\"auto, (max-width: 358px) 100vw, 358px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: \u00a0<strong><span style=\"color: #800000;\">5\/10<\/span><\/strong><\/p>\n<p>Colonial est un jeu de conqu\u00eates et de gestion de ressources qui fourmille de bonnes id\u00e9es.<\/p>\n<p>Chaque joueur poss\u00e8de un m\u00eame lot de 6 cartes actions dont il en jouera 5 \u00e0 chaque tour. \u00a0Chaque carte comporte 2 actions et il faudra choisir une des 2 pour chaque cartes ce qui rend les choix difficiles.<\/p>\n<p>Pour gagner, il faut engranger 10 PVs et \u00eatre exempt de toutes dettes. \u00a0Malheureusement, vous n&rsquo;allez pas pouvoir vous en sortir sans contracter quelques dettes.<\/p>\n<p>Tout d&rsquo;abord, vous allez conqu\u00e9rir des territoires. \u00a0Chaque territoire a une force qu&rsquo;il vous faudra battre gr\u00e2ce \u00e0 un jet de d\u00e9. \u00a0Oui, il y a du hasard dans Colonia mais contr\u00f4lable car si vous choisissez l&rsquo;action de progresser dans la capacit\u00e9 \u00ab\u00a0d\u00e9s\u00a0\u00bb, cela vous co\u00fbtera des sous mais vous ajouterez syst\u00e9matiquement 1, 2 ou 3 au r\u00e9sultat de votre d\u00e9. \u00a0De plus, si vous voulez conqu\u00e9rir un territoire adjacent \u00e0 l&rsquo;un des v\u00f4tres, vous b\u00e9n\u00e9ficiez d&rsquo;un \u00ab\u00a0+1\u00a0\u00bb suppl\u00e9mentaire au d\u00e9. \u00a0Bon, les rat\u00e9s arrivent n\u00e9anmoins, et \u00e7a peste autour de la table mais finalement assez peu (environ 1 fois par joueur par partie sauf si on tente le diable&#8230;). \u00a0Et conqu\u00e9rir un territoire vous rapporte 1 PV! 10 territoires de conquis et vos dettes rembours\u00e9es et c&rsquo;est la victoire&#8230; \u00a0mais ce serait trop simple!<\/p>\n<p>Outre le PV, chaque territoire vous offre une ressource que vous pourrez transporter, puis vendre pour enfin r\u00e9cup\u00e9rer le fruit de ce dur labeur, faire fortune et rembourser vos dettes que vous aurez contract\u00e9es pour r\u00e9aliser les diff\u00e9rentes actions. \u00a0Mais ce serait trop simple si vos adversaires ne vous mettaient pas des b\u00e2tons dans les roues. \u00a0En effet, ils peuvent tenter de prendre le contr\u00f4le de vos ressources en ajoutant leur pions de contr\u00f4le sur les v\u00f4tres. \u00a0Une action \u00ab\u00a0contr\u00f4le\u00a0\u00bb permet d&rsquo;ajouter 1 jeton sur un territoire mais si on d\u00e9cide d&rsquo;augmenter sa capacit\u00e9 (en r\u00e9alisant une autre action payante), on peut ajouter 2, 3 ou 4 jetons en une action. \u00a0C&rsquo;est un syst\u00e8me qui me fait penser un peu \u00e0 <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/09\/04\/hansa-teutonica-east-expansion\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Hansa Teutonica<\/span><\/a><\/span>. \u00a0Celui qui aura le plus de pions de contr\u00f4le, contr\u00f4lera la ressource et pourra la transporter et la vendre.<\/p>\n<p>De plus, vous allez bien devoir g\u00e9rer les r\u00e9voltes latentes des autochtones et votre argent car il vous sert \u00e0 augmenter vos flottes marchandes qui, elles, servent \u00e0 prendre le contr\u00f4le des territoires et \u00e0 transporter les marchandises mais \u00e9galement \u00e0 combattre les adversaires&#8230; \u00a0Et oui, dans Colonia, il y a des combats! \u00a0Une des actions consiste \u00e0 d\u00e9clarer la guerre \u00e0 un adversaire. \u00a0Pour cela, il faut \u00eatre plus haut que lui sur l&rsquo;\u00e9chelle diplomatique. \u00a0Si vous \u00eates plus bas, vous ne pouvez pas l&rsquo;attaquer et il vous restera une action vous permettant de progresser sur cette \u00e9chelle pour enfin satisfaire vos envies de revanches \ud83d\ude09 \u00a0Et une guerre, \u00e7a fait mal car tout y passe. \u00a0Les joueurs se battent \u00e0 grand coups de d\u00e9s (l\u00e0 y&rsquo;a pas mal de hasard&#8230;) sur tous les fronts: sur les territoires, sur la marchandise, sur votre tr\u00e9sorerie et vos bateaux. \u00a0Et \u00e0 chaque coup, vous en perdez. \u00a0Et je peux vous dire qu&rsquo;aussi bien l&rsquo;attaquant que le d\u00e9fenseur perdront des plumes. \u00a0Et une guerre dure autant de tours qu&rsquo;il le faut pour ruiner un des deux joueurs (qui aura alors quasi perdu la partie) mais pourra s&rsquo;arr\u00eater plus t\u00f4t si un des 2 joueurs abandonne au prix d&rsquo;un point de victoire donn\u00e9 \u00e0 l&rsquo;adversaire. \u00a0Autant vous dire qu&rsquo;on abandonne assez vite car il n&rsquo;est pas trop compliqu\u00e9 de regagner des PVs.<\/p>\n<p>Mais une guerre est tellement co\u00fbteuse, aussi bien pour l&rsquo;attaquant que pour le d\u00e9fenseur qu&rsquo;on ne l&rsquo;enclenche qu&rsquo;en dernier recours, autrement dit, s&rsquo;il n&rsquo;y a pas d&rsquo;autres moyens de stopper un joueur vers la victoire. \u00a0Et c&rsquo;est l\u00e0 o\u00f9 le b\u00e2t blesse dans Colonial. \u00a0M\u00eame avec un peu de hasard, tout le reste du jeu n&rsquo;est qu&rsquo;optimisation de ses actions et bonne gestion de ses ressources. \u00a0Celui qui arrivera le mieux \u00e0 g\u00e9rer tout \u00e7a sera le premier \u00e0 approcher de la victoire. \u00a0Puis, les autres vont commencer \u00e0 n\u00e9gocier pour savoir qui fera le sacrifice de l&rsquo;attaquer sous peine de le voir gagner. \u00a0Bien souvent, le joueur en seconde place pour la victoire va devoir se sacrifier pour stopper le joueur en t\u00eate en lan\u00e7ant une guerre contre lui. \u00a0Et puis, le jeu tourne sans fin. \u00a0On va \u00e0 chaque fois attaquer le joueur en t\u00eate et le jeu tourne en rond, se r\u00e9p\u00e8te, devient lassant. \u00a0Les 2 premi\u00e8res heures du jeu sont prenantes et les 2 derni\u00e8res lassantes. \u00a0Et ce n&rsquo;est bien \u00e9videmment pas celui qui aura r\u00e9ussi \u00e0 g\u00e9rer au mieux ses actions et ressources qui gagnera mais celui qui aura un peu de chance dans les n\u00e9gociations, qui aura r\u00e9ussi \u00e0 se faire oublier, qui aura r\u00e9ussi \u00e0 bien bluffer ou pire, qui aura eu la chance d&rsquo;\u00eatre sympa avec le kingmaker. \u00a0Et oui, il y a bien du kingmaking&#8230;<\/p>\n<p>Colonial est donc un jeu de conqu\u00eates extr\u00eamement bien fait mais qui souffre de tourner en rond d\u00e8s qu&rsquo;un joueur s&rsquo;approche de la victoire \u00e0 en devenir lassant et \u00e0 voir le vainqueur diff\u00e9rent de celui qui aura le mieux g\u00e9r\u00e9 ses ressources et optimis\u00e9 ses actions. \u00a0Dommage.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>PS: \u00a0Comme l&rsquo;a \u00e9crit Philrey dans son avis, il s&rsquo;av\u00e8re qu&rsquo;il existe une seconde version des r\u00e8gles qui corrige pas mal de d\u00e9fauts de la premi\u00e8re \u00e9dition. \u00a0J&rsquo;en profite pour pousser un petit coup de gueule: \u00a0Mais non d&rsquo;un chien chers \u00e9diteurs, portez une vigilance accrue sur vos r\u00e8gles! \u00a0Dans ce cas-ci, soit le jeu n&rsquo;a pas tourn\u00e9 assez avant d&rsquo;\u00eatre publi\u00e9. \u00a0Et \u00e7a, je peux le comprendre car il faut bien sortir le jeu un jour et \u00e0 trop le faire tourner, ben on perd du temps et donc de l&rsquo;argent. \u00a0Mais ici, les d\u00e9fauts nous ont saut\u00e9 aux yeux d\u00e8s la premi\u00e8re partie et donc j&rsquo;arrive au deuxi\u00e8me \u00ab\u00a0soit\u00a0\u00bb. \u00a0Soit les r\u00e8gles ont \u00e9t\u00e9 mal \u00e9crites ou mal relues. \u00a0Et \u00e7a, je pense sinc\u00e8rement que les \u00e9diteurs doivent porter une plus grande attention \u00e0 leurs r\u00e8gles. \u00a0Heureusement, pas tous les \u00e9diteurs sont dans ce cas. \u00a0Je suis occup\u00e9 de pr\u00e9parer un gros jeu (on y revient promis, je vous garde la surprise \ud83d\ude09 ) et certains d\u00e9tails des r\u00e8gles n&rsquo;\u00e9taient pas clairs pour moi. \u00a0J&rsquo;ai donc \u00e9t\u00e9 voir les forums sur BGG et j&rsquo;ai d\u00e9couvert plein de coquilles: des cartes mal imprim\u00e9es et qu&rsquo;il faut corriger, des r\u00e8gles \u00e0 corriger, des \u00e9claircissement judicieux,&#8230; \u00a0Et tout \u00e7a fait que les r\u00e8gles ne sont plus bonnes et que je me retrouve avec de nombreux prints de forums pour avoir une r\u00e8gle globale correcte mais o\u00f9 il est difficile de se retrouver tant des points sont corrig\u00e9s. \u00a0 On n&rsquo;a pas toujours le temps, et surtout pas le r\u00e9flexe d&rsquo;aller voir sur les forums. \u00a0Et dans le cas de Colonial, les r\u00e8gles \u00e9taient suffisamment claires pour ne pas devoir se coltiner la lecture des forums. \u00a0On a jou\u00e9 au jeu avec les r\u00e8gles de la boite. \u00a0R\u00e9sultat: 5 heures (4 heures de jeu + 1 heure d&rsquo;explication) \u00e0 jeter \u00e0 la poubelle! \u00a0Tout \u00e7a parce qu&rsquo;on n&rsquo;a pas suivi les bonnes r\u00e8gles,&#8230; enfin oui, on a suivi les bonnes r\u00e8gles du livret mais pas les corrig\u00e9es des forums!!! \u00a0Donc je dirais plut\u00f4t, tout \u00e7a parce que l&rsquo;\u00e9diteur n&rsquo;a pas pris la peine de bien relire ses r\u00e8gles et de fournir une bonne version des r\u00e8gles avec son jeu d\u00e8s le d\u00e9but. \u00a0Et ce genre d&rsquo;erreur peut \u00eatre un d\u00e9sastre pour un \u00e9diteur car les retours sur le jeu n&rsquo;en seront que mauvais car les gens auront jou\u00e9 aux mauvaises r\u00e8gles (enfin, les bonnes mais pas corrig\u00e9es \ud83d\ude42 ). \u00a0Alors le temps de corriger \u00e7a et c&rsquo;est d\u00e9j\u00e0 foutu. \u00a0J&rsquo;ai donc d\u00e9cid\u00e9 de maintenir ma \u00ab\u00a0mauvaise note\u00a0\u00bb et mauvais avis car il se base sur les bonnes r\u00e8gles du livret en attendant d&rsquo;y rejouer avec les bonnes r\u00e8gles (mais on a jou\u00e9 aux bonnes !?! \ud83d\ude00 ).<br \/>\nBref, mesdames et messieurs les \u00e9diteurs: vigilance, vigilance s&rsquo;il-vous pla\u00eet!<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a0 7\/10<\/span><\/strong><\/p>\n<p>Que d&rsquo;attentes j&rsquo;avais pour Colonial. Apr\u00e8s notre partie, il est vrai que je suis un peu d\u00e9\u00e7u. Pourtant, le jeu est bourr\u00e9 de bonnes id\u00e9es que je n&rsquo;avais pas encore vues ailleurs. Le plus surprenant pour moi fut le tableau de bord personnel de chaque joueur. Tout est comptabilis\u00e9 l\u00e0-dessus. Vos jetons passent ainsi de votre tr\u00e9sorerie vers votre flotte marchande (vous venez d&rsquo;investir en navires marchands), vers votre flotte de guerre (de nouveaux navires de guerres pour vous d\u00e9fendre), vers de nouvelles terres et colonies (vous venez d&rsquo;envahir ou de d\u00e9velopper vos comptoirs commerciaux). Pas de tuiles ressources, pas de jetons navires ou troupes. Vraiment bien foutu.<\/p>\n<p>Les actions, c&rsquo;est plus classique. Elle s&rsquo;effectuent par carte. Il faudra ici choisir 4 cartes parmi les 6 et les placer dans l&rsquo;ordre souhait\u00e9 face cach\u00e9e. Ces cartes seront r\u00e9v\u00e9l\u00e9e une par une, chacun \u00e0 son tour. Le fait d&rsquo;avoir 2 personnages (2actions diff\u00e9rentes) par carte permet de rendre le choix un peu moins lin\u00e9aire (en effet, un seul personnage fera l&rsquo;action). Apr\u00e8s les 4 cartes programm\u00e9e, on pourra encore joueur une \u00ab\u00a0carte de la derni\u00e8re chance\u00a0\u00bb de sa main (parmi les deux qui restent). On joue donc 5 cartes sur 6. L&rsquo;ordre est \u00e9videmment important et c&rsquo;est ici qu&rsquo;il faudra parfois essayer de lire les intentions des adversaires.<\/p>\n<p>Alors, pourquoi le souffl\u00e9 est tomb\u00e9? Et bien \u00e0 causes de r\u00e8gles de la premi\u00e8re \u00e9dition du jeu. En effet, suite \u00e0 notre partie, j&rsquo;ai pos\u00e9 quelques questions sur les forums et il s&rsquo;av\u00e8re qu&rsquo;il y a une 2\u00e8 \u00e9dition, avec quelques ajustements des r\u00e8gles. Mais ces ajustement sont terriblement importants, par exemple:<br \/>\n&#8211; un pr\u00eat n&rsquo;est pas automatiquement 10 mais 2x son niveau \u00e9conomique. Ensuite, chaque pr\u00eat constituera une pile et exigera le paiement d&rsquo;un int\u00e9r\u00eat;<br \/>\n&#8211; Les int\u00e9r\u00eats justement ne sont plus li\u00e9s aux jetons r\u00e9voltes que l&rsquo;on a sur son plateau de Nation. Donc, on paiera \u00e0 chaque fois, ce qui change la donne par rapport \u00e0 la version de la 1\u00e8re \u00e9dition;<br \/>\n&#8211; Les territoires adjacents, c&rsquo;est souvent \u00e9vident. Mais quand cela ne l&rsquo;est pas, la 2\u00e8 \u00e9dition a ajout\u00e9 des fl\u00e8ches, ce qui facilite la lecture;<br \/>\nLes deux premier changements changent totalement la mani\u00e8re de jouer et \u00e9vitera sans doute notre fin de partie, \u00e0 savoir:<br \/>\n&#8211; Plus de jetons dispo de sa couleur (pas clair dans les r\u00e8gles ce qu&rsquo;on fait). On a donc pris des pions d&rsquo;une autre couleur non utilis\u00e9e<br \/>\n&#8211; King making de fin de partie. En effet, plus question d&rsquo;accumuler des pr\u00eats comme on l&rsquo;a fait pour pouvoir plus ais\u00e9ment guerroyer.<\/p>\n<p>J&rsquo;en conclu donc que le jeu n&rsquo;\u00e9tait pas pr\u00eat \u00e0 \u00eatre lanc\u00e9 et qu&rsquo;il a fallu une 2\u00e8me \u00e9dition pour corriger le tir. Paradoxalement, la deuxi\u00e8me \u00e9dition a vu le jour suite au succ\u00e8s de la premi\u00e8re.<\/p>\n<p>J&rsquo;esp\u00e8re donc pouvoir convaincre mes amis de Vin d&rsquo;Jeu pour en refaire une partie avec les r\u00e8gles de cette deuxi\u00e8me \u00e9dition. Cela fera peut-\u00eatre revoir la cote \ud83d\ude09<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-6889\" title=\"707 Colonial 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2-1024x768.jpg\" alt=\"\" width=\"922\" height=\"691\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2013\/12\/707-Colonial-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 922px) 100vw, 922px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Colonial est un jeu de conqu\u00eates et de gestion de ressources qui fourmille de bonnes id\u00e9es. Chaque joueur poss\u00e8de un m\u00eame lot de 6 cartes actions dont il en jouera 5 \u00e0 chaque tour. \u00a0Chaque carte comporte 2 actions et il faudra choisir une des 2 pour&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":6890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[6,7],"class_list":["post-6888","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-philrey212","tag-swatsh","annee-344","auteurs-christophe-pont","editeurs-stratagem-ltd"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=6888"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6888\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/6890"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=6888"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=6888"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=6888"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}