{"id":6923,"date":"2014-02-15T17:16:48","date_gmt":"2014-02-15T16:16:48","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=6923"},"modified":"2014-02-15T17:16:48","modified_gmt":"2014-02-15T16:16:48","slug":"mount-everest","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/02\/15\/mount-everest\/","title":{"rendered":"Mount Everest"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-6925\" title=\"711 Mount Everest 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1.jpg\" alt=\"\" width=\"330\" height=\"400\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1.jpg 412w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1-247x300.jpg 247w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1-123x150.jpg 123w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-1-400x485.jpg 400w\" sizes=\"auto, (max-width: 330px) 100vw, 330px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: \u00a0<strong><span style=\"color: #800000;\"> 7\/10<\/span><\/strong><\/p>\n<p>Mount Everest est une sorte de version revisit\u00e9e et am\u00e9lior\u00e9e de K2 du m\u00eame auteur et sorti chez le m\u00eame \u00e9diteur.<\/p>\n<p>Chaque joueur prend le contr\u00f4le de 2 guides qui vont essayer de guider les touristes jusqu&rsquo;au sommet de l&rsquo;Everest puis de redescendre au camp sans laisser un de ses touristes mourir de faim, de froid ou par manque d&rsquo;oxyg\u00e8ne. \u00a0Oui, Mount Everest est cruel \ud83d\ude09 \u00a0Au plus de touristes vous aurez r\u00e9ussi \u00e0 guider sains et saufs, au plus de PVs vous gagnerez en sachant qu&rsquo;il y a des touristes sportifs et d&rsquo;autres moins et que c&rsquo;est assez facile de guider les sportifs tandis que les autres mourront plus vite mais rapporteront plus de points.<\/p>\n<p>Au d\u00e9but de chaque tour, les joueurs vont jouer 3 des 6 cartes qu&rsquo;ils ont en main et qu&rsquo;ils auront pr\u00e9alablement pioch\u00e9es dans leur pioche personnelle qui est en tout point identique \u00e0 celle des adversaires. \u00a0Une m\u00e9canique qui me fait penser au magnifique Turfmaster o\u00f9 le hasard intervient bien entendu mais au final, chacun tirera les m\u00eames cartes (mais pas au m\u00eame moment&#8230;). \u00a0Et celui qui aura eu le malheur de jouer les 3 cartes dont le total des points de mouvement est le plus \u00e9lev\u00e9 devra prendre un marqueur risque lui donnant une p\u00e9nalit\u00e9.<\/p>\n<p>Ensuite les joueurs vont pouvoir r\u00e9aliser des actions. \u00a0Certaines sont gratuites comme par exemple \u00e9quiper un guide en oxyg\u00e8ne, lui donner une tente ou des nouveaux clients. \u00a0Ce sont des actions gratuites mais le guide doit \u00eatre situ\u00e9 dans la base, un camp \u00e0 sa couleur ou sur la m\u00eame case que l&rsquo;autre guide de son camp pour pouvoir les r\u00e9aliser. \u00a0Evidemment, \u00e9quiper un guide ou lui donner de nouveaux clients ne se fait pas sans certaines contraintes et le guide a une capacit\u00e9 maximum de choses \u00e0 transporter. \u00a0Durant vos premi\u00e8res parties, vous allez beaucoup h\u00e9siter sur l&rsquo;\u00e9quilibre \u00e0 donner \u00e0 l&rsquo;\u00e9quipement de votre guide &amp; au nombre de touristes guid\u00e9s mais au fil des parties, ce ne sera plus un casse-t\u00eate au profit d&rsquo;un automatisme&#8230;<\/p>\n<p>Les autres actions n\u00e9cessitent l&rsquo;utilisation des 3 cartes jou\u00e9es par les diff\u00e9rents joueurs. \u00a0En effet, chaque carte montre un num\u00e9ro. \u00a0On additionne ces nombres afin de pouvoir monter de cases en cases. \u00a0En effet, chaque case a un nombre qu&rsquo;il faudra \u00e9galer pour pouvoir y monter ou descendre. \u00a0De plus, ces points permettent \u00e9galement d&rsquo;\u00e9tablir un camp.<\/p>\n<p>Voil\u00e0 pour les m\u00e9canismes principaux qui sont accompagn\u00e9s de la gestion de l&rsquo;oxyg\u00e8ne et de l&rsquo;acclimatation qui va d\u00e9cider de quels clients survivent ou pas (si vous n&rsquo;avez pas \u00e9t\u00e9 suffisamment pr\u00e9voyant bien entendu). \u00a0Mount Everest est un jeu sympathique dont le th\u00e8me est bien rendu sur le plateau, dans la gestion du camp, de ses actions et de ses cartes mouvements.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">______________<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-6924\" title=\"711 Mount Everest 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2.jpg\" alt=\"\" width=\"728\" height=\"922\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2.jpg 809w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2-237x300.jpg 237w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2-118x150.jpg 118w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/711-Mount-Everest-2-400x506.jpg 400w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Mount Everest est une sorte de version revisit\u00e9e et am\u00e9lior\u00e9e de K2 du m\u00eame auteur et sorti chez le m\u00eame \u00e9diteur. Chaque joueur prend le contr\u00f4le de 2 guides qui vont essayer de guider les touristes jusqu&rsquo;au sommet de l&rsquo;Everest puis de redescendre au camp sans&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":6925,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-6923","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-549","auteurs-adam-kaluza","editeurs-rebel-pl"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6923","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=6923"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/6923\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/6925"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=6923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=6923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=6923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}