{"id":7052,"date":"2014-03-09T15:20:10","date_gmt":"2014-03-09T14:20:10","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=7052"},"modified":"2014-10-21T22:35:05","modified_gmt":"2014-10-21T20:35:05","slug":"steam-park","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/03\/09\/steam-park\/","title":{"rendered":"Steam Park"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-7054\" title=\"724 Steam park 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1.jpg\" alt=\"\" width=\"350\" height=\"349\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-1-400x399.jpg 400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: \u00a0<strong><span style=\"color: #800000;\">7\/10<\/span><\/strong><\/p>\n<p>A la sortie d&rsquo;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/05\/06\/escape-la-malediction-du-temple\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Escape la mal\u00e9diction du temple<\/span><\/a><\/span>, j&rsquo;avais dit que ce jeu allait cr\u00e9er un \u00ab\u00a0genre\u00a0\u00bb. \u00a0Et bien je n&rsquo;avais pas tort. \u00a0Bon je n&rsquo;avais pas 100% raison non plus car les jeux se basant sur le syst\u00e8me d&rsquo;<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/05\/06\/escape-la-malediction-du-temple\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Escape<\/span><\/a><\/span> ne sont pas l\u00e9gions puisqu&rsquo;\u00e0 part <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/05\/06\/escape-la-malediction-du-temple\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Escape<\/span><\/a><\/span> et Steam Park, \u00e0 ma connaissance, seul <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/12\/04\/space-cadets-dice-duel\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Space Cadets Dice Duel<\/span><\/a><\/span> reprend le syst\u00e8me du lancement de d\u00e9s fr\u00e9n\u00e9tique. \u00a0 Vous savez, le syst\u00e8me o\u00f9 on jette et rejette les d\u00e9s fr\u00e9n\u00e9tiquement et rapidement car on est tenu par le temps.<\/p>\n<p>Mais dans Steam Park, c&rsquo;est, un peu, diff\u00e9rent. \u00a0En effet, alors que dans <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/05\/06\/escape-la-malediction-du-temple\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Escape<\/span><\/a><\/span>, le but \u00e9tait de d\u00e9placer son personnage et de d\u00e9couvrir les salles pour le faire fuir ce temple maudit, et que dans <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/12\/04\/space-cadets-dice-duel\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Space Cadets<\/span><\/a><\/span> le but \u00e9tait d&rsquo;\u00e9quiper et de diriger notre vaisseau spatial dans un combat galactique, dans Steam Park, les d\u00e9s servent \u00e0 obtenir les ressources n\u00e9cessaires \u00e0 la construction et \u00e0 la pub de notre parc d&rsquo;attraction.<\/p>\n<p>Les 3 auteurs de Steam Park ne sont d&rsquo;ailleurs pas des inconnus puisqu&rsquo;ils sont les auteurs habituels de la maison d&rsquo;\u00e9dition <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/editeurs\/cranio-creation\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Cranio Creation<\/span><\/a><\/span>. \u00a0Ils ont d\u00e9j\u00e0 cr\u00e9\u00e9 Dungeon Fighters et <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/01\/13\/1969\/\" target=\"_blank\"><span style=\"color: #0000ff;\">1969<\/span><\/a><\/span>.<\/p>\n<p>Les tours de Steam Park se d\u00e9roulent en 2 phases. \u00a0La premi\u00e8re, la plus importante, consiste \u00e0 jeter et rejeter vos d\u00e9s ressources jusque quand vous \u00eates satisfaits du r\u00e9sultat. \u00a0Mais attention \u00e0 ne pas \u00eatre trop difficile car le premier \u00e0 arr\u00eater de lancer ses d\u00e9s recevra le pion premier joueur, le second sera second joueur,&#8230; Et outre le fait qu&rsquo;avoir les bonnes ressources est important, l&rsquo;ordre du jeu l&rsquo;est encore plus.<\/p>\n<p>Ensuite, \u00e0 l&rsquo;aide des ressources produites par vos d\u00e9s, vous pourrez r\u00e9aliser diff\u00e9rentes actions: construire des attractions (au plus de ressources on y consacre, au plus gros sera l&rsquo;attraction), attirer de nouveaux clients (chaque d\u00e9 client vous fait attirer un nouveau client). \u00a0Vous prenez un des clients de la r\u00e9serve en l&rsquo;une des 5 couleurs possibles et vous l&rsquo;ajouter dans le sac en toile duquel vous piocherez un client au hasard. \u00a0Selon la couleur du client, s&rsquo;il vous reste des places libres dans des attractions de cette couleur, le client ira dans cette attraction sinon il s&rsquo;en ira. \u00a0Et les clients sont tr\u00e8s importants puisque ce sont eux qui vous rapporteront des PVs. \u00a0Vous pourrez aussi construire des stands qui vous apporteront certains bonus (pouvoir relancer un d\u00e9, pouvoir changer la face d&rsquo;un d\u00e9,&#8230;). \u00a0Enfin, certaines actions apporteront de la salet\u00e9 dans votre parc et la salet\u00e9 vous fera perdre des PVs. \u00a0Heureusement, il est toujours possible de nettoyer&#8230;<\/p>\n<p>L&rsquo;essence m\u00eame de Steam Park est donc le lancement fr\u00e9n\u00e9tique de d\u00e9s. \u00a0Il vous reste plus qu&rsquo;\u00e0 croiser les doigts pour que vos lancers vous donneront les ressources que vous esp\u00e9rez au plus vite sinon vous devrez vous contenter de moins pour ne pas \u00eatre dernier dans l&rsquo;ordre du tour. \u00a0La seconde action qui a son importance est l&rsquo;attrait de nouveaux clients. \u00a0Comme vous devrez les piochez dans un sac noir, vous devrez accepter une certaine dose de chance qui en fait un jeu fun et familial sans prise de t\u00eate et tr\u00e8s l\u00e9ger. \u00a0A noter que le mat\u00e9riel est de toute beaut\u00e9 gr\u00e2ce principalement aux attractions 3D magnifiquement illustr\u00e9es (voir photo).<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">PhilTap<\/span><\/strong>: <strong><span style=\"color: #800000;\">7,5\/10<\/span><\/strong><\/p>\n<p>SteamPark pourrait faire croire qu&rsquo;il fait partie des jeux dits \u00ab\u00a0d\u00e9cal\u00e9s\u00a0\u00bb ou \u00ab\u00a0D\u00e9lirants\u00a0\u00bb. Mais les illustrations bizarro\u00efdes de Marie Cardouat (Dixit) cache un jeu m\u00ealant gestion, rapidit\u00e9 et juste ce qu&rsquo;il faut de hasard. Dans Steam park, les joueurs doivent \u00e9chafauder un petit parc d&rsquo;attractions en construisant des man\u00e8ges, des stands divers, des WC et surtout faire en sorte d&rsquo;attirer des visiteurs : Des robots qui viendront salir tout \u00e7a&#8230; Le nettoyage du parc viendra alors vous pourrir dans votre d\u00e9veloppement.<\/p>\n<p>Le jeu se d\u00e9compose en plusieurs phases, mais la plus int\u00e9ressante est la planification d&rsquo;actions qui se fera \u00e0 l&rsquo;aide de jets de d\u00e9s, tous en m\u00eame temps ! La rapidit\u00e9 sera de mise, puisque si vous terminez en premier, vous allez pouvoir \u00e9conomiser des actions de nettoyage par un bonus r\u00e9serv\u00e9 aux joueurs les plus rapides.<\/p>\n<p>Steam Park s&rsquo;appuie sur un th\u00e8me original et poss\u00e8de un mat\u00e9riel abondant. M\u00eame s&rsquo;il ne colle pas vraiment \u00e0 la r\u00e9alit\u00e9, il n&rsquo;en reste pas moins un jeu amusant et d&rsquo;un niveau de difficult\u00e9 abordable aux joueurs occasionnels. Il plaira aux joueurs qui veulent un peu d&rsquo;originalit\u00e9. Steam Park m&rsquo;a donn\u00e9 la m\u00eame sensation que le fameux Galaxy Truckers&#8230;<\/p>\n<p>Pour conclure, je reprocherais une r\u00e8gle faite dans un papier tr\u00e8s tr\u00e8s fin et donc fragile \u00e0 manipuler. Pour le reste, c&rsquo;est plut\u00f4t bon.<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7053\" title=\"724 Steam park 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/724-Steam-park-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> A la sortie d&rsquo;Escape la mal\u00e9diction du temple, j&rsquo;avais dit que ce jeu allait cr\u00e9er un \u00ab\u00a0genre\u00a0\u00bb. \u00a0Et bien je n&rsquo;avais pas tort. \u00a0Bon je n&rsquo;avais pas 100% raison non plus car les jeux se basant sur le syst\u00e8me d&rsquo;Escape ne sont pas l\u00e9gions puisqu&rsquo;\u00e0 part Escape&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7054,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-7052","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-549","auteurs-aureliano-buonfino","auteurs-lorenzo-silva","auteurs-lorenzo-tucci-sorrentino","editeurs-cranio-creation","editeurs-iello"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=7052"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7052\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/7054"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=7052"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=7052"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=7052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}