{"id":7113,"date":"2014-03-31T20:03:56","date_gmt":"2014-03-31T19:03:56","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=7113"},"modified":"2014-10-21T22:34:17","modified_gmt":"2014-10-21T20:34:17","slug":"les-batisseurs-moyen-age","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/03\/31\/les-batisseurs-moyen-age\/","title":{"rendered":"Les b\u00e2tisseurs: Moyen-Age"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-7116\" style=\"margin: 5px;\" title=\"729 Les batisseurs 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-1.jpg\" alt=\"\" width=\"250\" height=\"283\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-1.jpg 250w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-1-132x150.jpg 132w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: \u00a0 <strong><span style=\"color: #800000;\">7,5 \/10<\/span><\/strong><\/p>\n<p>Dans Les B\u00e2tisseurs: Moyen-Age ce qui manque c&rsquo;est le \u00ab\u00a0du\u00a0\u00bb \ud83d\ude09 \u00a0Et comme \u00e7a sonne pas bien, on va juste l&rsquo;appeler \u00ab\u00a0Les B\u00e2tisseurs\u00a0\u00bb \ud83d\ude09<\/p>\n<p>Donc, Les B\u00e2tisseurs est le dernier jeu de Fr\u00e9d\u00e9ric Henry, l&rsquo;auteur des tr\u00e8s bons <span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2009\/11\/04\/the-adventurers\/\" target=\"_blank\">The Adventurers<\/a>,<\/span><\/span>\u00a0<span style=\"color: #0000ff;\"><span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2012\/10\/06\/timeline\/\" target=\"_blank\">Timeline<\/a>\u00a0<\/span><\/span>et <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/01\/rush-n-crush\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Rush n&rsquo;Crush<\/span><\/a><\/span>. \u00a0Les B\u00e2tisseurs, c&rsquo;est \u00e9galement le petit dernier de l&rsquo;\u00e9diteur de qualit\u00e9 qu&rsquo;est <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/editeurs\/bombyx\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Bombyx<\/span><\/a><\/span> qui nous a sorti de chouettes petits jeux tels que <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/04\/04\/gentlemen-cambrioleurs\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Gentlemen Cambrioleurs<\/span><\/a><\/span>\u00a0ou le tr\u00e8s bon <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2012\/09\/17\/noe\/\" target=\"_blank\"><span style=\"color: #0000ff;\">No\u00e9<\/span><\/a><\/span>.<\/p>\n<p>Les B\u00e2tisseurs est un petit jeu de cartes malin. \u00a0La premi\u00e8re chose qui m&rsquo;est venue \u00e0 l&rsquo;esprit lorsque j&rsquo;ai d\u00e9couvert la m\u00e9canique, c&rsquo;est \u00ab\u00a0c&rsquo;est simple mais fallait y penser\u00a0\u00bb.<\/p>\n<p>Il y a 2 types de cartes dans Les B\u00e2tisseurs:<br \/>\n1) Les <strong>b\u00e2timents<\/strong> qui rapportent de l&rsquo;argent et des PVs lorsqu&rsquo;ils sont construits et qui n\u00e9cessitent une combinaison de 4 ressources pour \u00eatre construits<br \/>\n2) Les <strong>ouvriers<\/strong> qui apportent divers combinaisons de ressources n\u00e9cessaires \u00e0 la construction des b\u00e2timents mais qui devront \u00eatre pay\u00e9s pour pouvoir livrer ces dites ressources.<\/p>\n<p>A son tour, on peut r\u00e9aliser <strong><span style=\"color: #800080;\">3 actions<\/span> <\/strong>gratuites et autant d&rsquo;actions payantes qu&rsquo;on veut en sachant qu&rsquo;il est tr\u00e8s rare (sauf \u00e0 la fin) qu&rsquo;on r\u00e9alise plus de 3 actions car les actions payantes co\u00fbtent tr\u00e8s cher. \u00a0Les actions possibles se r\u00e9sument aux 5 \u00ab\u00a0P\u00a0\u00bbs et sont:<br \/>\n&#8211; <strong>Prendre<\/strong> une carte b\u00e2timent parmi les 5 dispos\u00e9es et la poser devant soi face \u00ab\u00a0en construction\u00a0\u00bb<br \/>\n&#8211; <strong>Prendre<\/strong> une des 5 cartes ouvriers<br \/>\n&#8211; <strong>Poser<\/strong>\u00a0et <strong>payer<\/strong> un de ses ouvriers \u00e0 c\u00f4t\u00e9 d&rsquo;un b\u00e2timent pour lui apporter des ressources. \u00a0Quand un b\u00e2timent est fourni de toutes les ressources n\u00e9cessaires, il est retourn\u00e9 face construit et rapporte de l&rsquo;argent et des PVs.<br \/>\n&#8211; <strong>Passer<\/strong> et gagner de l&rsquo;argent en fonction du nombre d&rsquo;actions qu&rsquo;on sacrifie<\/p>\n<p>Le premier joueur \u00e0 atteindre 17 PVs gagne la partie. \u00a0Pas plus compliqu\u00e9 que \u00e7a.<\/p>\n<p><strong>Les B\u00e2tisseurs est<\/strong> donc un jeu assez simple, facile \u00e0 sortir et agr\u00e9able \u00e0 jouer. \u00a0Les B\u00e2tisseurs est tr\u00e8s tactique car on va attendre son tour pour r\u00e9fl\u00e9chir (bri\u00e8vement) aux actions qu&rsquo;on veut r\u00e9aliser et aux cartes qu&rsquo;on veut prendre ou jouer. \u00a0La tactique est assez simple: choisir les cartes ouvriers qui rapportent ensemble exactement les ressources n\u00e9cessaires \u00e0 la construction d&rsquo;un de ses b\u00e2timents, ni plus ni moins. \u00a0En effet, les ouvriers ont un co\u00fbt en fonction du nombre et du type de ressources qu&rsquo;ils apportent. \u00a0Si on apporte trop de ressource pour un b\u00e2timent on payera trop cher et \u00e7a risque de nous \u00eatre fatal. \u00a0Il faudra aussi un peu de chance pour pouvoir avoir l&rsquo;opportunit\u00e9 de piocher des ouvriers et des b\u00e2timents compatibles entre eux. \u00a0Les B\u00e2tisseurs n&rsquo;est pas tr\u00e8s profond et les r\u00e9flexions sont faciles. \u00a0J&rsquo;aurais aim\u00e9 un peu plus de profondeur avec, par exemple, des b\u00e2timents apportant certains bonus ou bien des types de b\u00e2timents qui rapportent des points bonus si on arrive \u00e0 les construire ensemble ou des trucs du genre. \u00a0Mais on me souffle \u00e0 l&rsquo;oreille que l&rsquo;auteur est occup\u00e9 de pr\u00e9parer d&rsquo;autres B\u00e2tisseurs plus \u00e9labor\u00e9s&#8230; miam miam \ud83d\ude00<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a0 7\/10<\/span><\/strong><\/p>\n<p>Beaucoup de \u00ab\u00a0fuzz\u00a0\u00bb autour des B\u00e2tisseurs. J&rsquo;\u00e9tais donc curieux d&rsquo;essayer cette petite bo\u00eete de jeu de gestion aux r\u00e8gles simples. Je ne vais pas dire que je suis un peu d\u00e9\u00e7u mais j&rsquo;avoue que je m&rsquo;attendais \u00e0 un peu plus. Malgr\u00e9 ses r\u00e8gles simples, les possibilit\u00e9s sont grandes, entendez qu&rsquo;il sera difficile \u00e0 un joueur de rester bloqu\u00e9 \u00e0 cause qu&rsquo;un joueur ait \u00ab\u00a0vol\u00e9\u00a0\u00bb un b\u00e2timent ou un ouvrier avant lui. Par contre, il faut \u00e9videmment optimiser tous ses coups ou du moins \u00ab\u00a0s&rsquo;\u00e9quiper\u00a0\u00bb d&rsquo;ouvriers assez polyvalents pour pouvoir r\u00e9pondre aux exigences d&rsquo;un max. de b\u00e2timents.<\/p>\n<p>Comme dit si bien Raf, facile \u00e0 sortir mais pas trop souvent (peut-\u00eatre) &#8230; \u00e0 voir.<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">Raf<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a07\/10<\/span><\/strong><\/p>\n<p>Les b\u00e2tisseurs est un jeu de pure optimisation, le d\u00e9but est assez lent car il faut d&rsquo;abord se choisir une s\u00e9rie d&rsquo;ouvriers pour pouvoir faire un max de combinaisons pour la construction des b\u00e2timents. lors de cette s\u00e9lection d&rsquo;ouvriers la chance peut plus ou moins vous aider, mais c&rsquo;est tr\u00e8s minime tellement il y a de solution ensuite il faut optimiser car les parties sont relativement serr\u00e9es et donc le moindre coup peut \u00eatre de trop. Les b\u00e2tisseurs a le gros avantage de pouvoir \u00eatre sorti facilement mais souvent \u00e7a c&rsquo;est autre chose<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a07,5\/10<\/span><\/strong><\/p>\n<p>Les B\u00e2tisseurs est un jeu qui s&rsquo;explique en quelques minutes, les parties sont courtes. \u00a0On pourra le sortir facilement et avec des publics vari\u00e9s. \u00a0Il demande de la r\u00e9flexion et le vainqueur cela celui qui aura optimis\u00e9 le plus (et accessoirement qui pourra profiter d&rsquo;un peu de chance dans le tirage des cartes). \u00a0 A noter que les actions suppl\u00e9mentaires, sont tr\u00e8s co\u00fbteuses. \u00a0En d\u00e9but de partie, on s&rsquo;en tient aux 3 premi\u00e8res permises.<\/p>\n<p>Le format est bien, les r\u00e8gles sont claires, la dur\u00e9e est bien, les illustrations sont tops, &#8230; \u00a0mais j&rsquo;ai trouv\u00e9 qu&rsquo;il manquait de fun. \u00a0Les tours se suivent et se ressemblent, il n&rsquo;y a pas beaucoup de strat\u00e9gies gagnantes, et l&rsquo;interaction est faible &#8230; (on peut prendre une carte qui int\u00e9resse le suivant, mais c&rsquo;est un tour perdu pour soi et comme les parties sont courtes, cela peut \u00eatre fatal !). \u00a0Il manque un petit truc pour en faire un grand jeu.<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">PhilTap<\/span><\/strong>: \u00a0<strong><span style=\"color: #800000;\">8\/10<\/span><\/strong><\/p>\n<p>Une joli bo\u00eete m\u00e9tallique avec un effet 3D gr\u00e2ce \u00e0 son bombage. Des illustrations style BD et un prix plus qu&rsquo;abordable. Il a tout pour attirer l\u2019\u0153il. La signature est de Fr\u00e9d\u00e9ric HENRY, auteur des c\u00e9l\u00e8bres TimeLine et Adventurers. Mais cette fois, il a d\u00e9cid\u00e9 de se lancer dans la gestion. \u00a0Avec les b\u00e2tisseurs ont restera quand m\u00eame dans un niveau l\u00e9ger et rapide, puisqu&rsquo;une partie dure environ une demi heure.<\/p>\n<p>Le principe est assez simple. Il y a deux paquets de cartes. Des grandes qui repr\u00e9sentent des b\u00e2timents du moyen \u00e2ge et des cartes de taille standard qui repr\u00e9sentent des ouvriers avec 5 sortes de comp\u00e9tences, ainsi que des pi\u00e8ces de monnaie. On \u00e9tale 5 cartes de chaque paquet que l&rsquo;on renouvelle avec une pioche. Les joueurs devront alors choisir des cartes b\u00e2timents ou ouvriers avec des actions, et faire les bons choix pour affecter ces ouvriers aux b\u00e2timents pour les construire, l\u00e0 aussi en d\u00e9pensant des actions et de l&rsquo;argent. Une fois les constructions r\u00e9alis\u00e9es, on gagne des points de victoire (17 pour gagner). On aura alors un petit jeu de gestion o\u00f9 les choix, les combinaisons seront importants pour \u00e9conomiser des actions et aller plus vite que ses adversaires.<\/p>\n<p>Les b\u00e2tisseurs est un jeu plaisant, facile \u00e0 sortir et tout \u00e0 fait dans l&rsquo;esprit du \u00ab\u00a0jeu en famille\u00a0\u00bb ou avec des amis joueurs occasionnels. Bien que le tirage des cartes apportent une part de hasard, il demeure un jeu captivant et agr\u00e9able. Une belle r\u00e9ussite&#8230;<\/p>\n<p>On regrettera juste que qu&rsquo;un sachet zipp\u00e9 ne soit pas fourni pour ranger les pi\u00e8ces.<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7114\" title=\"729 Les batisseurs 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/01\/729-Les-batisseurs-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Dans Les B\u00e2tisseurs: Moyen-Age ce qui manque c&rsquo;est le \u00ab\u00a0du\u00a0\u00bb \ud83d\ude09 \u00a0Et comme \u00e7a sonne pas bien, on va juste l&rsquo;appeler \u00ab\u00a0Les B\u00e2tisseurs\u00a0\u00bb \ud83d\ude09 Donc, Les B\u00e2tisseurs est le dernier jeu de Fr\u00e9d\u00e9ric Henry, l&rsquo;auteur des tr\u00e8s bons The Adventurers,\u00a0Timeline\u00a0et Rush n&rsquo;Crush. \u00a0Les B\u00e2tisseurs, c&rsquo;est&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[817,6,10,7],"class_list":["post-7113","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-pascal","tag-philrey212","tag-raf","tag-swatsh","annee-549","auteurs-frederic-henry","editeurs-bombyx"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7113","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=7113"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7113\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/7116"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=7113"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=7113"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=7113"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}