{"id":7338,"date":"2014-04-27T11:31:22","date_gmt":"2014-04-27T09:31:22","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=7338"},"modified":"2014-04-27T11:31:22","modified_gmt":"2014-04-27T09:31:22","slug":"lor-des-dragons","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/04\/27\/lor-des-dragons\/","title":{"rendered":"L&rsquo;or des dragons"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-7340\" style=\"margin: 5px;\" title=\"743 Or des dragons 1\" alt=\"\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-1.jpg\" width=\"230\" height=\"320\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-1.jpg 360w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-1-216x300.jpg 216w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-1-108x150.jpg 108w\" sizes=\"auto, (max-width: 230px) 100vw, 230px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: <strong><span style=\"color: #800000;\">\u00a08,5 \/10<\/span><\/strong><\/p>\n<p>Avec <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2011\/09\/15\/citadelles\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Citadelles<\/span><\/a><\/span>, l&rsquo;or des dragons est pour moi un des meilleurs jeux de Bruno Faidutti. \u00a0Pourtant, il date, 2001, \u00e7a ne nous rajeunit pas!<\/p>\n<p>L&rsquo;or des dragons est un jeu de n\u00e9gociation tr\u00e8s bien foutu. \u00a0On d\u00e9voile 4 cartes dragons qui vont indiquer le nombre de pierres pr\u00e9cieuses qu&rsquo;on va y placer directement et le nombre de pierres qu&rsquo;on va y placer lorsque un groupe d&rsquo;aventuriers l&rsquo;aura vaincu.<\/p>\n<p>Chaque joueur dispose d&rsquo;un groupe de 4 aventuriers. \u00a0Les 2 plus forts, ceux de valeur 3 et 4 n&rsquo;ont pas de pouvoir sp\u00e9cial si ce n&rsquo;est d&rsquo;\u00eatre tr\u00e8s fort! \u00a0\ud83d\ude42 \u00a0Les 2 plus faibles (de valeur 1 et 2) ont chacun un pouvoir sp\u00e9cial: le premier peut prendre toutes les pierres rouges s&rsquo;il est le seul aventurier de valeur 1 et le second peut voler une pierre \u00e0 l&rsquo;un des joueurs ayant plac\u00e9 un aventurier sous le m\u00eame dragon.<\/p>\n<p>Chacun \u00e0 son tour va placer un de ses aventuriers en dessous d&rsquo;un des dragons. \u00a0D\u00e8s que la force cumul\u00e9e des aventuriers sous un dragon d\u00e9passe la force de ce dragon, on y d\u00e9pose les pierres qui doivent encore y \u00eatre d\u00e9pos\u00e9es puis on retourne le sablier. \u00a0Les joueurs ayant plac\u00e9 un aventurier sous ce dragon, ont maintenant la dur\u00e9e du sablier pour se mettre d&rsquo;accord sur le partage. \u00a0S&rsquo;ils ne tombent pas d&rsquo;accord avant la fin du sablier, ils ne re\u00e7oivent rien et r\u00e9cup\u00e8rent leurs aventuriers. \u00a0S&rsquo;ils arrivent \u00e0 un accord, ils se partagent le butin. \u00a0On remplace ensuite le dragon vaincu par le suivant de la pioche.<\/p>\n<p>D\u00e8s que toutes les pierres pr\u00e9cieuses ont \u00e9t\u00e9 distribu\u00e9es, on compte les points de chacun. \u00a0Certaines pierres valent 3 points, d&rsquo;autres 1 points, et d&rsquo;autres 0 points mais rapportent 12 points si on en poss\u00e8de la majorit\u00e9. \u00a0De plus, une combinaison des 5 pierres de couleur diff\u00e9rente vous rapporte 5 points.<\/p>\n<p>On va donc placer ses aventuriers en dessous des dragons offrant les pierres qui nous int\u00e9ressent le plus tout en veillant \u00e0 ce que un nombre limit\u00e9 de joueurs puissent se partager le butin. \u00a0Ensuite, les joueurs vont n\u00e9gocier en fonction des forces en pr\u00e9sence la r\u00e9partition des pierres mais rien n&#8217;emp\u00eache un joueur d&rsquo;exiger plus que ce qu&rsquo;il aurait naturellement droit quitte \u00e0 faire \u00e9chouer toute la n\u00e9gociation. \u00a0Evidemment, lorsqu&rsquo;une n\u00e9gociation \u00e9choue, les joueurs ne participant pas au partage en seront les premiers b\u00e9n\u00e9ficiaires puisqu&rsquo;ils n&rsquo;auront d\u00e9pens\u00e9 aucun aventurier alors que ceux ayant d\u00e9pens\u00e9 des aventuriers n&rsquo;auront rien de plus qu&rsquo;eux&#8230;<\/p>\n<p>C&rsquo;est subtil et malin et le plaisir de jeu est bien pr\u00e9sent. \u00a0Il n&rsquo;est pas rare de voir de nombreux joueurs demandant une revanche&#8230;<\/p>\n<p style=\"text-align: center;\">____________<\/p>\n<p><strong><span style=\"color: #333399;\">Philrey212<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a0 \u00a07\/10<\/span><\/strong><\/p>\n<p>L&rsquo;or des Dragons est une d\u00e9couverte pour moi. Ce petit jeu de carte est principalement un jeu d&rsquo;influence ou chacun tentera de r\u00e9colter des pierres pr\u00e9cieuses pr\u00e9sentes sur les carte dragons. et comme on a tous les m\u00eames 4 cartes personnage pour vaincre les dragons, les tours sont rapides et les temps morts inexistant.<\/p>\n<p>Un petit b\u00e9mol dans notre partie \u00e0 3 joueurs, d\u00e9s que chacun de nous \u00e9tait pr\u00e9sent sous une carte dragon, aucun accord n&rsquo;est tomb\u00e9! Impossible. Du coup, il me semble ais\u00e9 dans cette configuration de bloquer une carte, en simplement refusant toute offre de partage de pierres. Je n&rsquo;ose imaginer \u00e0 4 ou 5 ou 6 joueurs!<\/p>\n<p>Si seuls 2 joueurs sont pr\u00e9sents, c&rsquo;est d\u00e9j\u00e0 plus facile. Evidemment, si vous \u00eates mauvais \u00ab\u00a0n\u00e9gociateur\u00a0\u00bb (un peu comme moi), vous aurez du mal \u00e0 gagner.<\/p>\n<p style=\"text-align: center;\">_____________<\/p>\n<p><strong><span style=\"color: #333399;\">Ren<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0 \u00a08\/10<\/span><\/strong><\/p>\n<p>Attention attention, pour nos (certainement tr\u00e8s nombreux, car tout le monde sait que Vin d&rsquo;jeu est LE site de r\u00e9f\u00e9rence du monde ludique francophone) amis Fran\u00e7ais qui nous lisent, une position pol\u00e9mique va venir, l\u00e0 tout de suite dans les instants qui viennent, l\u00e0 de tout bient\u00f4t l\u00e0 \u00e7a arrive, bam: L&rsquo;or des dragons est un des rares jeux potables de Bruno Faidutti (avec Citadelles). C&rsquo;est m\u00eame un tr\u00e8s tr\u00e8s chouette jeu. Le pitch est simple: chaque joueur a 4 aventuriers (guerrier, guerri\u00e8re, magicien, voleur, repr\u00e9sent\u00e9s par des cartes) qui vont \u00eatre utilis\u00e9s pour tuer des dragons. Comme les tue-t-on? Facile, on met une force totale sup\u00e9rieur \u00e0 leur force. Sachant que le guerrier vaut 4, la guerri\u00e8re 3, le voleur 2 et le magicien 1. Astuce qui fait le sel du jeu (et sans laquelle il n&rsquo;y aurait pas de jeu): tous les joueurs jouent un personnage chacun \u00e0 leur tour, et on peut \u00e9videmment se mettre \u00e0 plusieurs pour tuer un dragon. Et c&rsquo;est l\u00e0 que les romains s&#8217;empoignirent, puisqu&rsquo;une fois le dragon tu\u00e9, il va falloir se partager le magot, et ce dans un temps limit\u00e9 (dur\u00e9e d&rsquo;un sablier)&#8230; Or chaque dragon a un tr\u00e9sor, repr\u00e9sent\u00e9 par des pierres pr\u00e9cieuses, de l&rsquo;or, de l&rsquo;argent, des objets magiques. On marque des points \u00e0 la fin en fonction des tr\u00e9sors qu&rsquo;on d\u00e9tient: x points par majorit\u00e9 dans une couleur de pierre pr\u00e9cieuse, y points par or, z par argent&#8230; Il faut donc maximiser ses prises, tout en sachant que les autres joueurs vont faire la m\u00eame chose, voire carr\u00e9ment vous emb\u00eater expr\u00e8s en ne voulant pas partager comme vous voulez, bande de sales \u00e9go\u00efstes! Le plaisir principal du jeu consiste donc \u00e0 n\u00e9gocier, ce qui, dans tout groupe d&rsquo;amis normalement constitu\u00e9, donne quelque chose comme:<\/p>\n<p>X \u00ab\u00a0ok je propose \u00e7a\u00a0\u00bb<br \/>\nY \u00ab\u00a0dans tes r\u00eaves!\u00a0\u00bb<br \/>\nX \u00ab\u00a0bon ok alors faisons comme \u00e7a\u00a0\u00bb<br \/>\nY \u00ab\u00a0plut\u00f4t crever!\u00a0\u00bb<br \/>\nX \u00ab\u00a0bon ok je fais une concession je te donne un or en plus, l\u00e0 c&rsquo;est vachement \u00e9quilibr\u00e9!\u00a0\u00bb<br \/>\nZ (qui n&rsquo;a pas tu\u00e9 le dragon et n&rsquo;a rien \u00e0 voir avec l&rsquo;affaire) \u00ab\u00a0tain comme il essaye de t&rsquo;entuber, c&rsquo;en est \u00e9coeurant, te laisse pas faire!\u00a0\u00bb<br \/>\nX \u00ab\u00a0grouille le sablier est presque fini, on va se retrouver avec rien!\u00a0\u00bb<br \/>\nZ \u00ab\u00a0ha ben le sablier est fini, c&rsquo;est b\u00eate \u00e7a, quel dommage vous avez tu\u00e9 ce beau dragon pour rien, ha c&rsquo;est vraiment b\u00eate, je suis triste pour vous\u00a0\u00bb<\/p>\n<p>Bon d\u00e8s fois \u00e7a se termine bien et on partage. Mais toujours apr\u00e8s une bonne discussion! On ajoute \u00e0 \u00e7a que le voleur va toujours voler un tr\u00e9sor chez un autre joueur qui prenait part au partage, que le magicien prend en priorit\u00e9 les objets magique, et qu&rsquo;il y a moyen de jouer avec des cartes \u00e9v\u00e9nement qui ajoutent un peu d&rsquo;impr\u00e9vu, et on aura un tr\u00e8s chouette petit jeu d&rsquo;ap\u00e9ro, auquel je joue toujours avec grand plaisir, certes chaotique, plein de mauvaise foi voire m\u00eame de chance, mais qui est tout \u00e0 fait plaisant \u00e0 jouer de temps en temps. Le seul vrai d\u00e9faut que je lui accole est d&rsquo;\u00eatre un peu long pour un format de ce type.<\/p>\n<p style=\"text-align: center;\">_____________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7339\" title=\"743 Or des dragons 2\" alt=\"\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2-768x1024.jpg\" width=\"768\" height=\"1024\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2-112x150.jpg 112w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/02\/743-Or-des-dragons-2-400x533.jpg 400w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Arr\u00eatez de vous focaliser sur les seins de Ren, mais regardez plut\u00f4t ce magnifique Brunello Di Montalcino&#8230;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Avec Citadelles, l&rsquo;or des dragons est pour moi un des meilleurs jeux de Bruno Faidutti. \u00a0Pourtant, il date, 2001, \u00e7a ne nous rajeunit pas! L&rsquo;or des dragons est un jeu de n\u00e9gociation tr\u00e8s bien foutu. \u00a0On d\u00e9voile 4 cartes dragons qui vont indiquer le nombre de pierres&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7340,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[6,323,7],"class_list":["post-7338","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-philrey212","tag-ren","tag-swatsh","annee-105","auteurs-bruno-faidutti","editeurs-jeux-descartes"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=7338"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7338\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/7340"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=7338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=7338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=7338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}