{"id":7777,"date":"2014-05-03T11:30:42","date_gmt":"2014-05-03T09:30:42","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=7777"},"modified":"2014-05-16T11:53:57","modified_gmt":"2014-05-16T09:53:57","slug":"dungeon-twister-app-sur-une-plateforme-de-crowdfunding","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/05\/03\/dungeon-twister-app-sur-une-plateforme-de-crowdfunding\/","title":{"rendered":"Dungeon Twister App sur une plateforme de crowdfunding"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7778\" alt=\"777 Dungeont t\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t.jpg\" width=\"1003\" height=\"564\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t.jpg 1003w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t-300x168.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t-150x84.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/777-Dungeont-t-400x224.jpg 400w\" sizes=\"auto, (max-width: 1003px) 100vw, 1003px\" \/><\/a><\/p>\n<p><span style=\"line-height: 1.5em;\">L&rsquo;\u00e9quipe de conception de l&rsquo;app Dungeon Twister m&rsquo;a contact\u00e9 afin de vous parler de son projet.<\/span><\/p>\n<p>Je n&rsquo;ai pas grand chose \u00e0 dire puisque tout est bien expliqu\u00e9 sur <span style=\"color: #0000ff;\"><a href=\"http:\/\/fr.ulule.com\/dungeon-twister\/\" target=\"_blank\"><span style=\"color: #0000ff;\">le site<\/span><\/a><\/span>:\u00a0<span style=\"color: #0000ff;\"><a href=\"http:\/\/fr.ulule.com\/dungeon-twister\/\" target=\"_blank\"><span style=\"color: #0000ff;\">http:\/\/fr.ulule.com\/dungeon-twister\/<\/span><\/a><\/span><\/p>\n<p>Je voudrais n\u00e9anmoins pr\u00e9ciser quelques petites choses:<\/p>\n<ul>\n<li>Dungeon Twister est un des meilleurs jeux au monde: <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2010\/09\/29\/dungeon-twister-ext-34-joueurs\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Notre avis sur Vin d&rsquo;jeu<\/span><\/a><\/span>.<\/li>\n<li>L&rsquo;app sera disponible aussi bien sur IOS que sur Android, j&rsquo;en connais qui seront contents \ud83d\ude42<\/li>\n<li>Ils ont d\u00e9j\u00e0 d\u00e9pass\u00e9 de 150% leur objectif mais des soutiens suppl\u00e9mentaires ne serons jamais superflus \ud83d\ude09<\/li>\n<li>Les bonus que vous recevrez pour votre participation sont nombreux, vari\u00e9s et surprenants: des salles suppl\u00e9mentaires, des personnages suppl\u00e9mentaires, participer \u00e0 la cr\u00e9ation du tutoriel, des objets suppl\u00e9mentaires, une version pirate de certains personnages, une extension compl\u00e8te, des missions bonus dans le mode aventure, tester le jeu en avant premi\u00e8re, un cover iPhone, une tasse, un T-shirt, une BD, toutes les extensions \u00e0 venir gratuites, son nom dans les sponsors, <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/10\/09\/dungeon-twister-the-card-game-aide-de-jeu\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Dungeon Twister card game<\/span><\/a><\/span>, affronter Christophe Boelinger, et la fleur sur le g\u00e2teau: le premier prototype de Dungeon Twister cr\u00e9\u00e9 \u00e0 la main par l&rsquo;archimage en personne: Christophe Boelinger!<br \/>\nOn peut dire qu&rsquo;ils ont eu de l&rsquo;imagination pour tous ces goodies. \u00a0Il y en a clairement pour tous les go\u00fbts et difficile de ne pas y trouver son bonheur \ud83d\ude42<\/li>\n<\/ul>\n<p>Merci \u00e0 ceux qui soutiennent ce projet et vivement que l&rsquo;app sorte, j&rsquo;ai trop envie de jouer \u00e0 la b\u00eate et bien \u00e9videmment de vous en parler \ud83d\ude42<\/p>\n<p>Amusez-vous bien,<\/p>\n<p><span style=\"color: #333399;\">SwatSh<\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9quipe de conception de l&rsquo;app Dungeon Twister m&rsquo;a contact\u00e9 afin de vous parler de son projet. Je n&rsquo;ai pas grand chose \u00e0 dire puisque tout est bien expliqu\u00e9 sur le site:\u00a0http:\/\/fr.ulule.com\/dungeon-twister\/ Je voudrais n\u00e9anmoins pr\u00e9ciser quelques petites choses: Dungeon Twister est un des meilleurs jeux au monde: Notre avis sur&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7778,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-7777","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vin-djeu"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7777","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=7777"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7777\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/7778"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=7777"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=7777"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=7777"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}