{"id":7812,"date":"2014-06-18T21:32:03","date_gmt":"2014-06-18T19:32:03","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=7812"},"modified":"2014-06-18T21:32:03","modified_gmt":"2014-06-18T19:32:03","slug":"le-monde-est-fou","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/06\/18\/le-monde-est-fou\/","title":{"rendered":"Le Monde est Fou"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-7814\" alt=\"779 Le monde est fou 1\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1.jpg\" width=\"350\" height=\"350\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1.jpg 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1-150x150.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1-300x300.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-1-400x400.jpg 400w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>: \u00a0<strong><span style=\"color: #800000;\">7\/10<\/span><\/strong><\/p>\n<p>Le Monde est Fou est le dernier jeu de l&rsquo;\u00e9diteur <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/editeurs\/le-scorpion-masque\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Le Scorpion Masqu\u00e9<\/span><\/a><\/span> (<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/10\/grimpe\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Grimpe<\/span><\/a><\/span>, <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2013\/09\/23\/cest-pas-faux\/\" target=\"_blank\"><span style=\"color: #0000ff;\">C&rsquo;est pas faux<\/span><\/a><\/span>, <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2012\/08\/16\/quebec\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Qu\u00e9bec<\/span><\/a><\/span>, et le tr\u00e8s bon\u00a0<span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2010\/01\/01\/a-lheure-du-crime-ou-etiez-vous\/\" target=\"_blank\"><span style=\"color: #0000ff;\">A l&rsquo;heure du crime o\u00f9 \u00e9tiez-vous?<\/span><\/a><\/span>). \u00a0C&rsquo;est un petit jeu d&rsquo;ambiance familial.<\/p>\n<p>Le principe est tr\u00e8s simple. \u00a0Un joueur est d\u00e9sign\u00e9 comme psy et tous les autres comme des fous. \u00a0Un des fous pioche une carte et choisit une des 4 pathologies de la carte. \u00a0Par exemple: \u00eatre extr\u00eamement perfectionniste, avoir peur de la salet\u00e9, toujours prononcer un nom d&rsquo;un fruit dans chacune de ses phrases, ne jamais prononcer les \u00ab\u00a0S\u00a0\u00bb, croire que le psy est un cannibale, se prendre pour un chien qui parle,&#8230; \u00a0Il communique alors son choix de pathologie aux autres fous (les r\u00e8gles proposent de choisir ensemble la pathologie mais lorsque vous \u00eates trop nombreux, cela ralentit trop le jeu).<\/p>\n<p>Puis le psy pose des questions \u00e0 chacun des joueurs. \u00a0Les questions doivent \u00eatre g\u00e9n\u00e9rales du type: Qu&rsquo;avez-vous fait aujourd&rsquo;hui? \u00a0Comment allez-vous? \u00a0Aimez-vous les animaux? \u00a0Quel est votre travail?,&#8230; \u00a0Les fous r\u00e9pondent alors aux questions du psy en donnant des indices au psy sur leur pathologie. \u00a0 Cela peut \u00eatre assez subtil, par exemple, le fou qui est hyper perfectionniste dira qu&rsquo;il est toujours pile poil \u00e0 l&rsquo;heure, jamais 1 minute trop t\u00f4t ni une minute trop tard ou celui qui doit toujours dire un fruit dans ses phrases pourra dire qu&rsquo;il tombe souvent dans les pommes ou qu&rsquo;il trouve qu&rsquo;il est venu voir son psy pour des prunes car il n&rsquo;a pas une belle poire \ud83d\ude00 \u00a0Bref, cela peut donner de belles r\u00e9pliques qui font souvent rire les autres fous tant on admire l&rsquo;imagination ou les entourloupes des autres fous. \u00a0Le but \u00e9tant pour le psy de d\u00e9couvrir la pathologie dont souffrent les fous alors que pour les fous, c&rsquo;est plut\u00f4t l&rsquo;hilarit\u00e9 des autres fous qu&rsquo;ils recherchent car un vote a lieu a la fin de chaque tour pour le fou qui a mieux plu aux autres.<\/p>\n<p>Le Monde est fou lasse assez vite et apr\u00e8s 3-4 tours de table on pr\u00e9f\u00e8re s&rsquo;arr\u00eater l\u00e0 car, \u00e0 de nombreux joueurs, le jeu dure un peu trop longtemps. \u00a0L<span style=\"line-height: 1.5em;\">es points sont peu importants et on s&rsquo;en fou ( \ud83d\ude09 ) un peu de gagner des points. Le plus important est de s&rsquo;amuser et de rigoler. \u00a0Et le jeu y parvient! \u00a0Le tout est d&rsquo;avoir des joueurs suffisamment imaginatifs autour de la table comme souvent dans ce type de jeu. \u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-7813\" alt=\"779 Le monde est fou 2\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2-1024x768.jpg\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/05\/779-Le-monde-est-fou-2-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Voici quelques exemples de pathologies, comme vous pouvez le voir, y&rsquo;a pas mal de th\u00e8me qui peuvent apporter beaucoup de fun.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Le Monde est Fou est le dernier jeu de l&rsquo;\u00e9diteur Le Scorpion Masqu\u00e9 (Grimpe, C&rsquo;est pas faux, Qu\u00e9bec, et le tr\u00e8s bon\u00a0A l&rsquo;heure du crime o\u00f9 \u00e9tiez-vous?). \u00a0C&rsquo;est un petit jeu d&rsquo;ambiance familial. Le principe est tr\u00e8s simple. \u00a0Un joueur est d\u00e9sign\u00e9 comme psy et tous les&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":7814,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7],"class_list":["post-7812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","annee-779","auteurs-chris-james","editeurs-le-scorpion-masque"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=7812"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/7812\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/7814"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=7812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=7812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=7812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}