{"id":8551,"date":"2014-09-10T11:39:31","date_gmt":"2014-09-10T09:39:31","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=8551"},"modified":"2014-09-10T11:39:31","modified_gmt":"2014-09-10T09:39:31","slug":"merci-philibert","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/09\/10\/merci-philibert\/","title":{"rendered":"Merci Philibert!"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/09\/831-Philibert.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-8552\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/09\/831-Philibert.png\" alt=\"831 Philibert\" width=\"284\" height=\"163\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/09\/831-Philibert.png 284w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/09\/831-Philibert-150x86.png 150w\" sizes=\"auto, (max-width: 284px) 100vw, 284px\" \/><\/a><\/p>\n<p>Ce petit mot juste pour remercier notre partenaire <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.philibertnet.com\/fr\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Philibert<\/span><\/a><\/span>, d&rsquo;abord de nous soutenir depuis d\u00e9j\u00e0 2 ans, mais aussi parce que les philiboys, sans rien nous demander, ont mis notre humble site en avant (\u00ab\u00a0blog du mois\u00a0\u00bb)\u00a0dans leur derni\u00e8re newsletter avec ce petit mot tellement sympathique qu&rsquo;il nous va droit au c\u0153ur:<\/p>\n<table width=\"700\">\n<tbody>\n<tr>\n<td rowspan=\"2\" width=\"30\"><\/td>\n<\/tr>\n<tr>\n<td width=\"19\"><\/td>\n<td width=\"404\"><strong>Vin d&rsquo;jeu<\/strong>Le monde francophone du jeu est tr\u00e8s riche. Apr\u00e8s vous avoir parl\u00e9 d&rsquo;un \u00e9diteur qu\u00e9becois, voici un blog belge ! Ce petit groupe fort sympathique, amateur de vin et de jeux, propose sur leur blog de nombreuses analyses (la liste des jeux comment\u00e9s est impressionnante) avec des infos, des photos, des notations et avis de chaque membre ayant test\u00e9 le jeu. En bonus, quelques photos de leurs voyages chaque ann\u00e9e \u00e0 Essen o\u00f9 avec leur sweat rose, on ne peut pas les louper !<\/td>\n<td width=\"0\"><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>Merci <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.philibertnet.com\/fr\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Philibert<\/span><\/a><\/span>, \ud83d\ude42<\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ce petit mot juste pour remercier notre partenaire Philibert, d&rsquo;abord de nous soutenir depuis d\u00e9j\u00e0 2 ans, mais aussi parce que les philiboys, sans rien nous demander, ont mis notre humble site en avant (\u00ab\u00a0blog du mois\u00a0\u00bb)\u00a0dans leur derni\u00e8re newsletter avec ce petit mot tellement sympathique qu&rsquo;il nous va droit&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":8552,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-8551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vin-djeu"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/8551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=8551"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/8551\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/8552"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=8551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=8551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=8551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}