{"id":876,"date":"2010-05-24T18:00:00","date_gmt":"2010-05-24T17:00:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2010\/05\/24\/empire-builder\/"},"modified":"2010-06-20T18:18:41","modified_gmt":"2010-06-20T17:18:41","slug":"empire-builder","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2010\/05\/24\/empire-builder\/","title":{"rendered":"Empire Builder"},"content":{"rendered":"<p><span style=\"color: #663366;\"><br \/>\n<\/span><\/p>\n<p><a href=\"http:\/\/1.bp.blogspot.com\/_ea2yja0GmY8\/S-5zRXV7B9I\/AAAAAAAAA4g\/cUU7O2yTOu8\/s1600\/empirebuilder00.jpg\" onblur=\"try {parent.deselectBloggerImageGracefully();} catch(e) {}\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5471437339462666194\" style=\"margin: 0px 10px 10px 0px; width: 206px; float: left; height: 257px; cursor: hand;\" src=\"http:\/\/1.bp.blogspot.com\/_ea2yja0GmY8\/S-5zRXV7B9I\/AAAAAAAAA4g\/cUU7O2yTOu8\/s400\/empirebuilder00.jpg\" border=\"0\" alt=\"\" \/><\/a><\/p>\n<div style=\"text-align: left;\"><span style=\"color: #3366ff;\">Philrey212:<\/span> <span style=\"color: #cc0000;\">8\/10<\/span><\/div>\n<p>Empire Builder est un jeu de \u00ab\u00a0construction\u00a0\u00bb de voies de chemin de fer sur le continent nord am\u00e9ricain.<\/p>\n<p>La grosse particularit\u00e9 est qu&rsquo;on dessine sur le tableau de jeu. Ce qui laisse une libert\u00e9 totale au joueur pour \u00e9tendre son r\u00e9seau comme bon lui semble.<\/p>\n<p>Empire Builder est un jeu o\u00f9 il faut g\u00e9rer son argent et l&rsquo;investir au mieux \u00e0 l&rsquo;expansion de son r\u00e9seau. Et ce tout en faisant bien attention de pouvoir r\u00e9pondre aux demandes en ressources et autre biens des villes. En effet, chaque joueur a en permanence trois cartes, chacune avec trois demandes de livraison.<\/p>\n<p>Vous aurez devin\u00e9 qu&rsquo;une fois le r\u00e9seau \u00e9tabli, les trains se d\u00e9placent pour charger et livrer les diff\u00e9rents produits.<\/p>\n<p>L&rsquo;int\u00e9r\u00eat du jeu r\u00e9side principalement dans la conception de son r\u00e9seau. Le pickup &amp; delivery est quant \u00e0 lui, \u00e0 la longue, un peu r\u00e9p\u00e9titif.<\/p>\n<p>Attention, Empire Builder est long, tr\u00e8s long. A trois, nous n&rsquo;avons pas termin\u00e9 la partie, apr\u00e8s &#8230; plus de 4 heures de jeu. Mais franchement, on ne s&rsquo;ennuie pas!<\/p>\n<p>Maintenant, on peut appliquer des variantes pour acc\u00e9l\u00e9rer le jeu, comme augmenter la vitesse des trains, d\u00e9marrer avec plus d&rsquo;argent, etc.<\/p>\n<p>Encore une bonne soir\u00e9e Vin d&rsquo;Jeu!<\/p>\n<p><span style=\"color: #3366ff;\">Beno\u00eet:<\/span> <span style=\"color: #cc0000;\">8,1<span><strong> <\/strong>\/10<\/span><\/span><br \/>\nJ&rsquo;ai beaucoup aim\u00e9 notre \u00ab\u00a0longue\u00a0\u00bb partie de \u00ab\u00a0Empire Builder\u00a0\u00bb. C&rsquo;est un jeu \u00e0 l&rsquo;ancienne que l&rsquo;on commence \u00e0 14:30 en terminant la bouteille de Gevrey Chambertin (ou un cigare pour les plus inconscients) au coin du feu et ou on sait que l&rsquo;on va passer une bonne apr\u00e8s-midi, voir soir\u00e9e;-) Pas d&rsquo;autre jeu pr\u00e9vu \u00e0 l&rsquo;agenda parce que l&rsquo;on veut rester dans un environnement connu et confortable.<\/p>\n<p>La surprise est que l&rsquo;on dessine ses voies de chemin de fer au feutre directement sur le plateau. Cel\u00e0 donne une impression g\u00e9niale d&rsquo;ouverture, de cr\u00e9ativit\u00e9, de renouvellement permanent&#8230;<\/p>\n<p>La gestion de son cash est essentielle &#8211; une erreur peut vous laisser exsangue sans aucune chance de revenir dans la partie. Mais bon, c&rsquo;est quand m\u00eame pas trop dur, il ne faut pas sortir la calculette, juste le boulier&#8230;<\/p>\n<p>Pas de grande strat\u00e9gie ici et pas mal (trop?) de hazard; on optimise \u00ab\u00a0simplement\u00a0\u00bb en fonction de son dernier tirage en construisant des voies que l&rsquo;on pourra utiliser un maximum de fois.<\/p>\n<p>En r\u00e9sum\u00e9, Empire Builder est un tr\u00e8s chouette jeu pour les familles qui ont aim\u00e9 les Aventuriers du rail.<\/p>\n<div><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5471435500713474786\" style=\"text-align: center; margin: 0px auto 10px; width: 400px; display: block; height: 249px; cursor: hand;\" src=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/S-5xmVd8-uI\/AAAAAAAAA4Y\/APOVBfjLhHU\/s400\/empirebuilder.jpg\" border=\"0\" alt=\"\" \/><\/div>\n<div>Voici le tableau de jeu avec les voies des diff\u00e9rents joueurs. Sur les c\u00f4t\u00e9s, les carte &lsquo;contrat&rsquo; des chaque joueur et les cartes train. On remarque en bas que le train est charg\u00e9 de trois marchandises.<\/div>\n","protected":false},"excerpt":{"rendered":"<p> Empire Builder est un jeu de \u00ab\u00a0construction\u00a0\u00bb de voies de chemin de fer sur le continent nord am\u00e9ricain. La grosse particularit\u00e9 est qu&rsquo;on dessine sur le tableau de jeu. Ce qui laisse une libert\u00e9 totale au joueur pour \u00e9tendre son r\u00e9seau comme bon lui semble. Empire Builder est&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":9088,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[8,6],"class_list":["post-876","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-benoit","tag-philrey212","annee-234","auteurs-bill-fawcett","auteurs-darwin-bromley","editeurs-mayfair-games"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/876","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=876"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/876\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9088"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=876"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=876"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=876"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}