{"id":8825,"date":"2014-10-11T16:42:42","date_gmt":"2014-10-11T14:42:42","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=8825"},"modified":"2014-10-11T16:42:42","modified_gmt":"2014-10-11T14:42:42","slug":"lost-legacy-hyakunen-senso-to-ryu-no-miko","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/10\/11\/lost-legacy-hyakunen-senso-to-ryu-no-miko\/","title":{"rendered":"Lost Legacy: Hyakunen Senso to Ryu no Miko"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-8827\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-1.jpg\" alt=\"844 Lost Legacy 1\" width=\"300\" height=\"409\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-1.jpg 367w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-1-220x300.jpg 220w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-1-110x150.jpg 110w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-Lost-Legacy-2.jpg\"><br \/>\n<\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0\u00a0<strong><span style=\"color: #800000;\">8\/10<\/span><\/strong><\/p>\n<p>Lost Legacy: Hyakunen Senso to Ryu no Miko est une variante\u00a0stand alone de Lost Legacy que, honte sur moi, je n&rsquo;ai encore jamais eu l&rsquo;occasion de jouer.\u00a0 La boite contient 2 sets de 16 cartes diff\u00e9rentes permettant de jouer au m\u00eame jeu, avec les m\u00eames r\u00e8gles mais avec des cartes aux pouvoirs diff\u00e9rents.\u00a0 2 jeux originaux en un, waouw!\u00a0 Les r\u00e8gles se basent certainement sur Lost Legacy mais les cartes sont diff\u00e9rentes.<\/p>\n<p>Lost Legacy: Hyakunen Senso to Ryu no Miko (vive le copi\u00e9\/coll\u00e9 \ud83d\ude09 ) est un jeu de Seiji Kanai, mais oui vous savez, l&rsquo;auteur de l&rsquo;\u00e9tonnant et non moins plaisant <a href=\"http:\/\/www.vindjeu.eu\/2014\/09\/03\/love-letter-kanai-edition\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Love Letter<\/span><\/a>.\u00a0 Et on reconna\u00eet facilement sa patte: jeu minimaliste de 16 cartes.\u00a0 Tous les joueurs ont une carte en main et en piochent une au d\u00e9but de leur tour puis en jouent une, appliquent son effet et passent la main au joueur suivant.\u00a0 Et voil\u00e0 toutes les r\u00e8gles \ud83d\ude42 , tr\u00e8s proche de <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2014\/09\/03\/love-letter-kanai-edition\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Love Letter <\/span><\/a><\/span>somme toute.<\/p>\n<p>L&rsquo;originalit\u00e9 de Lost Legacy qui en fait toute sa saveur et son c\u00f4t\u00e9 indispensable pour tout amateur de <span style=\"color: #0000ff;\"><a href=\"http:\/\/www.vindjeu.eu\/2014\/09\/03\/love-letter-kanai-edition\/\" target=\"_blank\"><span style=\"color: #0000ff;\">Love Letter <\/span><\/a><\/span>est sa fin enqu\u00eatrice.\u00a0 En effet, \u00e0 la fin, quand il ne reste plus de carte dans la pioche, les joueurs vont, chacun \u00e0 leur tour en commen\u00e7ant par le joueur ayant la carte de plus faible valeur, annoncer qui ils pensent qui a la carte Lost Legacy (elle peut soit se trouver dans la main d&rsquo;un des joueurs soit dans une pile de carte(s) sp\u00e9cifique sur la table appel\u00e9e Ruines).\u00a0 S&rsquo;il le joueur a trouv\u00e9, il l&#8217;emporte imm\u00e9diatement, sinon, on passe au joueur suivant.\u00a0 Inutile de vous dire qu&rsquo;il vaut mieux rester avec une carte de faible valeur \u00e0 la fin du jeu tant les possibilit\u00e9s de se douter fortement de qui a la carte Lost Legacy sont nombreuses.\u00a0 En effet, les pouvoirs des cartes permettent de regarder d&rsquo;autres, d&rsquo;\u00e9changer,&#8230; mais aussi, et tout comme dans Love Letter, d&rsquo;\u00e9liminer un joueur voire m\u00eame de l&#8217;emporter avant la fin.<\/p>\n<p>Le plus gros ennui de cette version est que les cartes sont remplies de sigles Japonnais embrouillant un peu les joueurs malgr\u00e9 la traduction anglaise inscrite en petit juste en dessous.\u00a0 Malgr\u00e9 ce petit d\u00e9faut qui emp\u00eache d&rsquo;y jouer avec les enfants (sauf en \u00e9crivant dessus \u00e9ventuellement), Lost Legacy: Hyakunen Senso to Ryu no Miko est vraiment une chouette alternative \u00e0 Love Letter am\u00e9liorant et modifiant les plaisirs de jeu.<\/p>\n<p style=\"text-align: center;\">______________________<\/p>\n<p><strong><span style=\"color: #333399;\">Pascal<\/span><\/strong>:<strong><span style=\"color: #800000;\">\u00a0\u00a0\u00a0\u00a0 6,5 \/10<\/span><\/strong><\/p>\n<p>Le jeu est tr\u00e8s similaire \u00e0 Love Letter dans sa m\u00e9canique, pour ne pas dire identique. Mais autant j&rsquo;appr\u00e9cie les parties \u00e0 LL, autant ici, je suis rest\u00e9 dubitatif.<\/p>\n<p>On n&rsquo;a fait que 2 parties (de 5 minutes chacune).\u00a0 Lors des 2 parties, j&rsquo;ai eu la m\u00eame impression : devoir choisir entre 2 cartes identiques, \u00eatre \u00e9limin\u00e9 tr\u00e8s t\u00f4t, et aucune id\u00e9e des cartes que les autres joueurs pourraient avoir en main.\u00a0 Il faudrait probablement plusieurs parties pour d\u00e9couvrir les subtilit\u00e9s, mais elles ne m&rsquo;ont pas saut\u00e9 aux yeux imm\u00e9diatement.<\/p>\n<p>Love Letter est dans ma ludoth\u00e8que, pas besoin d&rsquo;y rajouter Lost Legacy !<\/p>\n<p style=\"text-align: center;\">______________________<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-8831\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3-1024x768.jpg\" alt=\"844 LL 3\" width=\"1024\" height=\"768\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3-150x112.jpg 150w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/10\/844-LL-3-400x300.jpg 400w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Lost Legacy: Hyakunen Senso to Ryu no Miko est une variante\u00a0stand alone de Lost Legacy que, honte sur moi, je n&rsquo;ai encore jamais eu l&rsquo;occasion de jouer.\u00a0 La boite contient 2 sets de 16 cartes diff\u00e9rentes permettant de jouer au m\u00eame jeu, avec les m\u00eames r\u00e8gles mais avec des&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":8827,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-8825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-779","auteurs-hayato-kisaragi","auteurs-masato-uesugi","auteurs-seiji-kanai","editeurs-one-draw"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/8825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=8825"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/8825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/8827"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=8825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=8825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=8825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}