{"id":89,"date":"2009-09-11T20:03:00","date_gmt":"2009-09-11T19:03:00","guid":{"rendered":"http:\/\/www.vindjeu.eu\/2009\/09\/11\/perikles-2006-3-a-5j-expert\/"},"modified":"2010-06-06T16:13:15","modified_gmt":"2010-06-06T15:13:15","slug":"perikles","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2009\/09\/11\/perikles\/","title":{"rendered":"Perikles"},"content":{"rendered":"<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5380288971904222402\" style=\"margin: 0px 10px 10px 0px; width: 180px; float: left; height: 250px;\" src=\"http:\/\/2.bp.blogspot.com\/_ea2yja0GmY8\/SqqgUF9NhMI\/AAAAAAAAAY8\/au2ZORHP57A\/s400\/74+Perikles+1.JPG\" border=\"0\" alt=\"\" \/><strong><span style=\"color: #9999ff;\">Benoit<\/span><\/strong>:<span style=\"color: #ff6666;\"><strong> 7\/10<\/strong><\/span><br \/>\nPour la description du jeu, voir les commentaires avis\u00e9s de Phil et SwatSh. Je retiens principalement:<br \/>\n&#8211; m\u00e9canismes complexes et originaux (merci Wallace!)<br \/>\n&#8211; th\u00e8me pas tr\u00e8s bien rendu<br \/>\n&#8211; hasard fort (trop?) pr\u00e9sent ce qui rend la strat\u00e9gie long terme quasi inexistante<br \/>\n&#8211; longueur de chacune des phases avec un peak au lancement des d\u00e9s pour la r\u00e9solution des combats<br \/>\n&#8211; grande capacit\u00e9 de nuisance des joueurs: dans cette partie, un joueur (moi) \u00e9tait nettement en avance apr\u00e8s le deuxi\u00e8me tour ce qui a excit\u00e9 la hargne des autres (eux) avec pour cons\u00e9quence 6 malheureux points marqu\u00e9s en phase 3 et une deuxi\u00e8me position au final.<br \/>\nEn r\u00e9sum\u00e9, achet\u00e9 ce jeu si vous \u00eates un fan de Wallace et si vous avez d\u00e9j\u00e0 les autres: Age of Steam, Tinner&rsquo;s trail ou Brass!<\/p>\n<p><span style=\"color: #9999ff;\"><strong><span id=\"SPELLING_ERROR_0\" class=\"blsp-spelling-error\">Philrey<\/span>212<\/strong><\/span>:<span style=\"color: #ff6666;\"><strong> 6\/10<\/strong><\/span><br \/>\nJ&rsquo;ai pass\u00e9 une agr\u00e9able soir\u00e9e \u00e0 jouer \u00e0 Perikles! Je ne peux pourtant pas dire que le jeu m&rsquo;a agr\u00e9ablement surpris.<br \/>\nMartin Wallace est r\u00e9put\u00e9 pour ces jeux qui respectent bien le th\u00e8me, ses m\u00e9canismes originaux, le peu de chance qu&rsquo;il y apporte, etc.<br \/>\nMon opinion sur Perikles est toute autre:<br \/>\n1) La chance est omnipr\u00e9sente et influence le jeu \u00e0 divers moment. En phase 1, lors de la prise de tuile d&rsquo;influence. M\u00eame s&rsquo;il y en a 10 de disponible, il manque tojours celle que vous avez besoin! En phase 5, lors de la r\u00e9solution des combats: multiples jets de d\u00e9s.<br \/>\nSur ce point, je pense que Wallace a d\u00e9j\u00e0 fait beaucoup mieux!<br \/>\n2) Pas de strat\u00e9gie long terme possible. On joue au tour par tour pour prendre le max de points possibles.<br \/>\n3) J&rsquo;ai bien appr\u00e9ci\u00e9 le principe d&rsquo;\u00e9lection de leader des villes. Il est r\u00e9parti sur les 2 premi\u00e8res phases de jeu. Ce qui est dommage est lorsqu&rsquo;il n&rsquo;y a pas de leader sur une ville \u00e0 la fin de la phase 1, on fait des tours de table jusqu&rsquo;\u00e0 ce que toutes les villes aient 2 leaders. Chacun propose alors un joueur comme leader. Il est donc r\u00e9gulier de voir deux candidats dans une ville o\u00f9 le troisi\u00e8me a une grosse majorit\u00e9. A perte et profit pour le tour en cour.<br \/>\n4) Le th\u00e8me est un choix comme un autre. Mais cela aurait pu \u00eatre une bataille de clans  \u00e0 l&rsquo;\u00e9poque de la pr\u00e9histoire!<br \/>\n5) La partie a quand m\u00eame dur\u00e9e 3 heures, pour 3 tours de jeu, \u00e0 3 joueurs.<\/p>\n<p>D\u00e9s lors, m\u00eame si la partie \u00e9tait agr\u00e9able, les r\u00e8gles et m\u00e9canismes pas trop compliqu\u00e9s, Perikles ne m&rsquo;a pas convaincu.<\/p>\n<p><strong><span style=\"color: #9999ff;\"><span id=\"SPELLING_ERROR_1\" class=\"blsp-spelling-error\">SwatSh<\/span><\/span><\/strong>:<strong><span style=\"color: #ff6666;\"> 7,9\/10<\/span><\/strong><br \/>\n<span id=\"SPELLING_ERROR_2\" class=\"blsp-spelling-error\">Perikles<\/span> fut une bonne surprise. Vu son prix attractif pour l&rsquo;instant et vu que son auteur est un de mes pr\u00e9f\u00e9r\u00e9s (Martin <span id=\"SPELLING_ERROR_3\" class=\"blsp-spelling-error\">Wallace<\/span> \u00e9videmment) et malgr\u00e9 le (trop) peu d&rsquo;\u00e9cho que j&rsquo;ai eu de ce jeu, j&rsquo;ai craqu\u00e9 \ud83d\ude09 Et j&rsquo;ai bien fait!<\/p>\n<p>Martin <span id=\"SPELLING_ERROR_4\" class=\"blsp-spelling-error\">Wallace<\/span> n&rsquo;a pas \u00e0 rougir de ce jeu, il lui correspond bien: m\u00e9canique super bien huil\u00e9e et comme <span id=\"SPELLING_ERROR_5\" class=\"blsp-spelling-error\">d&rsquo;hab<\/span> originale. Et qui dit originale pour <span id=\"SPELLING_ERROR_6\" class=\"blsp-spelling-error\">Wallace<\/span> dit tordue!<\/p>\n<p>Jugez plut\u00f4t:<br \/>\n<strong><span style=\"color: #009900;\">1<span id=\"SPELLING_ERROR_7\" class=\"blsp-spelling-error\">ere<\/span> phase<\/span><\/strong>: on choisit une tuile parmi 10 qui nous permet de placer soit:<br \/>\n&#8211; 2 de nos cubes dans une ville<br \/>\n&#8211; un seul cube mais on peut retirer un cube adverse (ou un des siens &#8211; <span id=\"SPELLING_ERROR_8\" class=\"blsp-spelling-corrected\">\u00e7a<\/span> peut \u00eatre int\u00e9ressant)<br \/>\n&#8211; un seul cube mais on peut placer un de ses cubes comme candidat<\/p>\n<p>Chaque fois qu&rsquo;un joueur prend une tuile, elle est remplac\u00e9e par une de la pioche. Ici intervient un peu de hasard qui peut \u00eatre frustrant par la nouvelle tuile pioch\u00e9e qui peut \u00eatre celle que tout le monde attend et qui ne b\u00e9n\u00e9ficiera qu&rsquo;au joueur qui aura eu la chance de la piocher.<\/p>\n<p><strong><span style=\"color: #009900;\">2<span id=\"SPELLING_ERROR_9\" class=\"blsp-spelling-error\">eme<\/span> phase<\/span><\/strong>: parmi les cubes plac\u00e9s, on choisit un candidat parmi les 2 possibles \u00e0 \u00eatre leader de la ville en question (on peut donc choisir un autre candidat qu&rsquo;un des siens, ce qui est souvent int\u00e9ressant)<\/p>\n<p><span style=\"color: #009900;\"><strong>3<span id=\"SPELLING_ERROR_10\" class=\"blsp-spelling-error\">eme<\/span> phase<\/strong><\/span>: On \u00e9lit les leader parmi les 2 candidats en fonction des majorit\u00e9s sur les villes. Si \u00e9galit\u00e9, le candidat se trouvant a gauche (case alpha) gagne. On remarque donc l&rsquo;int\u00e9r\u00eat de la tuile nous permettant de placer un de nos cubes comme candidat en phase 1.<\/p>\n<p>Ici, le m\u00e9canisme est un peu frustrant car comme on \u00e9lit le leader parmi les 2 candidats, il se peut qu&rsquo;un joueur ait la majorit\u00e9 dans la ville sans avoir de candidat et ne b\u00e9n\u00e9ficie donc pas de sa <span id=\"SPELLING_ERROR_11\" class=\"blsp-spelling-corrected\">supr\u00e9matie<\/span>. De part ce fait, sur les 6 villes, \u00e0 3 joueurs, \u00e0 chaque tour, un de nous 3 \u00e9tait leader de 3 villes, un autre de 2 et le dernier de 1. Assez frustrant pour ce dernier qui \u00e9tait majoritaire dans d&rsquo;autres villes.<\/p>\n<p>Les leader gagneront des points de victoire en fin de partie en fonction des combats: au plus la ville aura subit de pertes, au moins de points vaudra un leader en fin de partie.<br \/>\nC&rsquo;est surtout ici qu&rsquo;intervient la strat\u00e9gie du jeu puisque on devra adapter notre strat\u00e9gie en fonction des leaders qu&rsquo;on a: quelles villes attaquer en phase 4 et quelles villes d\u00e9fendre absolument.<\/p>\n<p><strong><span style=\"color: #009900;\">4<span id=\"SPELLING_ERROR_12\" class=\"blsp-spelling-error\">eme<\/span> phase<\/span><\/strong>: on prend et place des tuiles arm\u00e9es des villes o\u00f9 on est leader et on les places sur le champs de bataille en attaquant une des 5 villes \u00e0 attaquer.<\/p>\n<p>L&rsquo;ordre est tr\u00e8s important puisqu&rsquo;on a vraiment int\u00e9r\u00eat \u00e0 placer ses arm\u00e9es en dernier car on voit alors o\u00f9 les autres joueurs ont plac\u00e9 les leurs. Et l&rsquo;ordre est \u00e9tablit en fonction des tuiles pioch\u00e9es en phase 1: au moins on a choisit de tuile nous permettant de placer 2 arm\u00e9es, au plus tard on pourra placer ses arm\u00e9es.<br \/>\nIl est donc vachement plus int\u00e9ressant en phase 1 de choisir des tuiles nous permettant de placer 2 cubes car on gagnera plus vite les majorit\u00e9s, mais d&rsquo;un autre c\u00f4t\u00e9, les tuiles ne permettant de placer qu&rsquo;un seul cube nous permettent de placer nos arm\u00e9es plus tard.<br \/>\nAvec <span id=\"SPELLING_ERROR_13\" class=\"blsp-spelling-error\">Wallace<\/span> c&rsquo;est tordu je vous le disais \ud83d\ude09<\/p>\n<p><strong><span style=\"color: #009900;\">5<span id=\"SPELLING_ERROR_14\" class=\"blsp-spelling-error\">eme<\/span> phase<\/span><\/strong>: On r\u00e9sout les combats en calculant les diff\u00e9rences de forces entre l&rsquo;attaquant et le d\u00e9fenseur. Sur base de cette diff\u00e9rence, on lance 2 d\u00e9s, et on doit d\u00e9passer un certain minimum.<br \/>\nPar exemple: l&rsquo;attaquant a une force de 4 et le d\u00e9fenseur de 2. En jetant 2 d\u00e9s, les 2 joueurs devront d\u00e9passer un minimum (qu&rsquo;on trouve sur une table, dans le cas pr\u00e9sent sous la colonne \u00ab\u00a02:1\u00a0\u00bb) pour gagner une bataille: l&rsquo;attaquant doit faire minimum 6 et le d\u00e9fenseur 9. D\u00e8s qu&rsquo;un joueur gagne 2 batailles, il gagne la guerre et empoche la tuile combat qui lui donne des points de victoire.<br \/>\nDans cette phase, le hasard intervient \u00e9videmment, mais ne g\u00eane vraiment pas. Dans notre partie, en aucun cas le hasard a fait gagner un joueur plus faible. Que du contraire, ce hasard apporte son lot de <span id=\"SPELLING_ERROR_15\" class=\"blsp-spelling-error\">fun<\/span>, stress et (faux) espoir qui fait p\u00e9tiller le jeu.<br \/>\nPetit reproche tout de m\u00eame: on doit lancer vraiment beaucoup les d\u00e9s, \u00e7a devient un peu lassant \u00e0 la fin.<\/p>\n<p>Voil\u00e0 en gros, le jeu se joue en 3 (seulement!) tours et se boucle en 3 &#8230; heures!!!! 1 heure par tour, c&rsquo;est long.<\/p>\n<p><span id=\"SPELLING_ERROR_16\" class=\"blsp-spelling-error\">Perikles<\/span> a donc quelques d\u00e9fauts (frustration, jets de d\u00e9s, dur\u00e9e) mais jouit de m\u00e9canismes originaux et d&rsquo;une r\u00e9elle strat\u00e9gie de jeu. Ce qui donne au final un tr\u00e8s bon jeu qui aurait encore pu \u00eatre meilleur s&rsquo;il n&rsquo;avait eu ses quelques d\u00e9fauts&#8230;<\/p>\n<p><a href=\"http:\/\/4.bp.blogspot.com\/_ea2yja0GmY8\/SqqfiEbDW_I\/AAAAAAAAAY0\/g9pQ3IotFyE\/s1600-h\/74+Perikles+2.JPG\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5380288112499055602\" style=\"margin: 0px auto 10px; text-align: center; width: 300px; display: block; height: 400px;\" src=\"http:\/\/4.bp.blogspot.com\/_ea2yja0GmY8\/SqqfiEbDW_I\/AAAAAAAAAY0\/g9pQ3IotFyE\/s400\/74+Perikles+2.JPG\" border=\"0\" alt=\"\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p> Pour la description du jeu, voir les commentaires avis\u00e9s de Phil et SwatSh. Je retiens principalement: &#8211; m\u00e9canismes complexes et originaux (merci Wallace!) &#8211; th\u00e8me pas tr\u00e8s bien rendu &#8211; hasard fort (trop?) pr\u00e9sent ce qui rend la strat\u00e9gie long terme quasi inexistante &#8211; longueur de chacune des&#46;&#46;&#46;<\/p>\n","protected":false},"author":2,"featured_media":8988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4849],"tags":[8,6,7],"class_list":["post-89","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-expert","tag-benoit","tag-philrey212","tag-swatsh","auteurs-martin-wallace","editeurs-esdevium","editeurs-fantasy-flight-games","editeurs-warfrog"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/89","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=89"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/89\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/8988"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=89"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=89"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=89"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}