{"id":9615,"date":"2014-12-20T12:13:13","date_gmt":"2014-12-20T11:13:13","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=9615"},"modified":"2014-12-20T12:13:13","modified_gmt":"2014-12-20T11:13:13","slug":"animal-suspect","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2014\/12\/20\/animal-suspect\/","title":{"rendered":"Animal Suspect"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9620\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1.jpg\" alt=\"874 Animal Suspect 1\" width=\"300\" height=\"401\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1.jpg 374w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1-224x300.jpg 224w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1-119x160.jpg 119w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-1-254x340.jpg 254w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0 <strong><span style=\"color: #800000;\">8,5 \/10<\/span><\/strong><\/p>\n<p>Animal Suspect est un nouveau jeu de mimes de <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/bruno-faidutti\/\" target=\"_blank\">Bruno Faidutti<\/a>.<\/p>\n<p>Animal Suspect propose une combinaison de mime, un peu comme dans <a href=\"http:\/\/www.vindjeu.eu\/2014\/07\/23\/mimtoo-famille\/\" target=\"_blank\">Mim Too<\/a>, \u00a0entre un animal et un sentiment qui, \u00e9trangement,\u00a0marche tr\u00e8s bien.\u00a0 En effet, alors que dans <a href=\"http:\/\/www.vindjeu.eu\/2014\/07\/23\/mimtoo-famille\/\" target=\"_blank\">Mim Too\u00a0<\/a>on a plut\u00f4t tendance \u00e0 imiter l\u2019animal et ensuite imiter le reste et donc de ne pas imiter les 2 en m\u00eame temps, dans Animal Suspect, les r\u00e8gles l\u2019interdisent puisqu\u2019elles obligent les joueurs \u00e0 faire une grimace fig\u00e9e\u00a0!\u00a0 Ici, il n\u2019est pas possible de faire un mime puis un autre, tout doit \u00eatre dans une seule et m\u00eame grimace.<\/p>\n<p>Mais que doit-on reproduire\u00a0?\u00a0 Un animal li\u00e9 \u00e0 une \u00e9motion\u00a0!\u00a0 Hou l\u00e0\u00e0\u00e0\u00e0 la bonne id\u00e9e\u00a0!\u00a0\ud83d\ude42\u00a0 Voir photo du bas pour des exemples.<\/p>\n<p>Ca n\u2019a pas l\u2019air facile d\u2019arriver \u00e0 faire deviner ces combinaisons en une seule mimique me direz-vous, et vous aurez raison\u00a0!\u00a0 Et c\u2019est l\u00e0 la seconde bonne id\u00e9e de Bruno Faidutti\u00a0: on a un plateau avec 6 cartes \u00e9motions et 6 cartes animal.\u00a0 Le joueur qui va devoir faire deviner va tirer secr\u00e8tement au hasard la combinaison animal\/\u00e9motion qu\u2019il va devoir faire deviner.\u00a0 Les autres joueurs vont devoir deviner lequel des 6 animaux le gus imite et laquelle des \u00e9motions il exprime.\u00a0 D\u00e8s qu\u2019un joueur pense avoir trouv\u00e9, il s\u2019empare du tot&#8230; heu du canard noir et fait pou\u00eat avec\u00a0\ud83d\ude42\u00a0 S\u2019il trouve il gagne un point et le mimeur aussi sinon, il ne peut plus faire de proposition pour ce mime et les autres peuvent faire une autre proposition.<\/p>\n<p>Animal Suspect tourne tr\u00e8s bien et atteint son but pour un jeu d\u2019ambiance\u00a0: d\u00e9clencher des fous rires\u00a0!\u00a0 Il renouvelle tr\u00e8s bien le jeu de mime d\u2019une mani\u00e8re tr\u00e8s originale puisque les joueurs vont devoir faire des grimaces pour faire deviner les combinaisons.\u00a0 Je n&rsquo;avais encore jamais vu un jeu o\u00f9 il fallait faire des grimaces pour gagner\u00a0\ud83d\ude00 G\u00e9nial\u00a0!<\/p>\n<p style=\"text-align: center;\">_______________________________________________________________________________________<\/p>\n<p><strong><span style=\"color: #333399;\">Tapimoket<\/span><\/strong>:\u00a0 <strong><span style=\"color: #800000;\">6,5 \/10<\/span><\/strong><\/p>\n<p>Dans la cat\u00e9gorie jeu d\u00e9cal\u00e9, je demande \u00ab\u00a0Animal suspect\u00a0\u00bb&#8230;<\/p>\n<p>Voyons, voyons, cinq animaux&#8230; une loutre, une pieuvre, une m\u00e9duse &#8230; Puis cinq adjectifs&#8230; \u00a0 Press\u00e9, ivre, pervers&#8230;.<\/p>\n<p>Pas d&rsquo;enfants \u00e0 table ? &#8230;ok, on peut laisser la derni\u00e8re carte&#8230;<\/p>\n<p>Allez, maintenant il faut mimer tout \u00e7a<\/p>\n<p>&#8230;<\/p>\n<p>Comment \u00e7a je ne dois pas le faire\u00a0s\u00e9par\u00e9ment\u00a0? Mais comment veux tu que je fasse une m\u00e9duse hallucin\u00e9e ?<\/p>\n<p>&#8230;<\/p>\n<p>Bon&#8230; c&rsquo;est amusant&#8230; Assez proche de <a href=\"http:\/\/www.vindjeu.eu\/2014\/07\/23\/mimtoo-famille\/\" target=\"_blank\">Mim Too<\/a>.<\/p>\n<p>Mais est ce le jeu que je ressortirais r\u00e9guli\u00e8rement en famille&#8230; \u00a0?<\/p>\n<p style=\"text-align: center;\">\u00a0___________________________________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-9619\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2.jpg\" alt=\"874 Animal Suspect 2\" width=\"1200\" height=\"900\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2.jpg 4000w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2-1024x768.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-2-453x340.jpg 453w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">_______________________________________________________________________________________________________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-9618\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-768x1024.jpg\" alt=\"874 Animal Suspect 3\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-3-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Avec le Santenay, vous vous sentez rena\u00eetre \ud83d\ude42<\/p>\n<p style=\"text-align: center;\">__________________________________________________________________________________________________<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-9616\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-768x1024.jpg\" alt=\"874 Animal Suspect 4\" width=\"720\" height=\"960\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-768x1024.jpg 768w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-225x300.jpg 225w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-120x160.jpg 120w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-183x245.jpg 183w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/11\/874-Animal-Suspect-4-255x340.jpg 255w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p style=\"text-align: center;\">Un vin injustement m\u00e9connu tant il est particulier et excellent, le Savagnin du Jura, je ne saurais que vous le conseiller pour l&rsquo;ap\u00e9ro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Animal Suspect est un nouveau jeu de mimes de Bruno Faidutti. Animal Suspect propose une combinaison de mime, un peu comme dans Mim Too, \u00a0entre un animal et un sentiment qui, \u00e9trangement,\u00a0marche tr\u00e8s bien.\u00a0 En effet, alors que dans Mim Too\u00a0on a plut\u00f4t tendance \u00e0 imiter l\u2019animal&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":9620,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[7,877],"class_list":["post-9615","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-famille","tag-swatsh","tag-tapimoket","annee-779","auteurs-bruno-faidutti","auteurs-nathalie-grandperrin","editeurs-gigamic"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/9615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=9615"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/9615\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9620"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=9615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=9615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=9615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}