{"id":9801,"date":"2015-01-14T17:58:21","date_gmt":"2015-01-14T16:58:21","guid":{"rendered":"http:\/\/www.vindjeu.eu\/?p=9801"},"modified":"2015-01-14T17:58:21","modified_gmt":"2015-01-14T16:58:21","slug":"dogs-of-war","status":"publish","type":"post","link":"https:\/\/www.vindjeu.eu\/prd\/2015\/01\/14\/dogs-of-war\/","title":{"rendered":"Dogs of War"},"content":{"rendered":"<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-9803\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1.png\" alt=\"891 Dogs of War 1\" width=\"500\" height=\"446\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1.png 500w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1-300x267.png 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1-160x142.png 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1-274x245.png 274w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-Dogs-of-War-1-381x340.png 381w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p><strong><span style=\"color: #333399;\">SwatSh<\/span><\/strong>:\u00a0 <strong><span style=\"color: #800000;\">7\/10<\/span><\/strong><\/p>\n<p>Dogs of War est le dernier jeu de <a href=\"http:\/\/www.vindjeu.eu\/auteurs\/paolo-mori\/\" target=\"_blank\">Paolo Mori<\/a>, l\u2019auteur du g\u00e9nialissime <a href=\"http:\/\/www.vindjeu.eu\/2010\/11\/20\/vasco-da-gama\/\" target=\"_blank\">Vasco Da Gama <\/a>(un de <a href=\"http:\/\/www.vindjeu.eu\/vin-djeu-dlannee\/vin-djeu-dlannee-2010\/\" target=\"_blank\">nos coups de coeur 2010<\/a>) et des tr\u00e8s sympas <a href=\"http:\/\/www.vindjeu.eu\/2013\/07\/24\/augustus\/\" target=\"_blank\">Augustus <\/a>&amp; <a href=\"http:\/\/www.vindjeu.eu\/2013\/06\/22\/libertalia\/\" target=\"_blank\">Libertalia<\/a>.<\/p>\n<p>Depuis Vasco, l\u2019orientation ludique de Paolo est plut\u00f4t tourn\u00e9e vers le familial \/ familial +.\u00a0 Et Dogs of War ne faillit pas \u00e0 cette tendance.<\/p>\n<p>En effet, le jeu est tr\u00e8s simple.\u00a0 Les r\u00e8gles s\u2019expliquent en 10 minutes.\u00a0 Le plateau montre 3 batailles.\u00a0 Dans chaque bataille s\u2019affrontent 2 familles.\u00a0 Il y a donc (3 x 2 =) 6 familles en tout.\u00a0 Les familles qui s\u2019affrontent sont tir\u00e9es au hasard lors de chacune des 4 manches.<\/p>\n<p>A votre tour, vous allez devoir d\u00e9cider quelle(s) famille(s) vous voulez soutenir en pla\u00e7ant l\u2019une de vos figurines (elles sont magnifiques d\u2019ailleurs, voil\u00e0 un des grands avantages d\u2019\u00eatre pass\u00e9 par Kickstarter\u00a0\ud83d\ude09 ) sur la fiche de la famille que vous voulez soutenir.\u00a0 Cette fiche comporte diff\u00e9rents types de bonus et la case o\u00f9 vous placerez votre figurine d\u00e9terminera le bonus que vous obtiendrez.\u00a0 En plus de votre figurine, vous allez aussi devoir placer un soldat qui soutiendra l\u2019arm\u00e9e de cette famille.\u00a0 Ces soldats co\u00fbtent de l\u2019argent et leur prix varie de 1 \u00e0 4 en fonction de la force du soldat qui peut aller de 1 \u00e0 7.\u00a0 <a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignright wp-image-9804\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3.jpg\" alt=\"891 DoW 3\" width=\"650\" height=\"488\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-3-453x340.jpg 453w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a>Autrement dit, un soldat de valeur 7 ne co\u00fbtera que 4 alors qu\u2019un de valeur 1 co\u00fbtera 1\u00a0!\u00a0 Vous pensez alors que c\u2019est plus int\u00e9ressant d\u2019acheter les plus puissants et vous aurez raison mais il faudra aussi penser \u00e0 avoir assez d\u2019argent et \u00e0 en avoir assez pour pouvoir placer toutes vos figurines (quand on place 1 figurine, on place 1 soldat\u00a0!)&#8230; Ensuite, vous d\u00e9placez le marqueur de bataille vers la famille que vous soutenez d\u2019un nombre de cases \u00e9gal \u00e0 la force du soldat que vous avez d\u00e9pos\u00e9.<\/p>\n<p>Puis, chaque autre joueur fait de m\u00eame et on continue \u00e0 jouer tant qu\u2019on peut ou veut placer une figurine et un soldat.\u00a0 Vous allez donc voir progressivement des alliances se former sur chaque bataille.\u00a0 Plusieurs joueurs vont soutenir la m\u00eame famille sur une bataille et vont peut-\u00eatre soutenir 2 familles oppos\u00e9es dans une autre bataille.\u00a0 Evidemment, au plus t\u00f4t vous soutenez une famille au plus vous risquez que les autres soutiennent la famille oppos\u00e9e \u00e0 votre plus grand malheur.\u00a0 Etre plus tard dans l\u2019ordre du tour est un s\u00e9rieux avantage.\u00a0 N\u00e9anmoins, au plus t\u00f4t vous jouez, au plus de choix vous aurez quant au bonus de placement de votre figurine.\u00a0 Et ce bonus est loin d\u2019\u00eatre n\u00e9gligeable puisqu\u2019il peut \u00eatre de l\u2019argent n\u00e9cessaire au recrutement de vos futurs soldats, une nouvelle figurine, des soldats, des cartes bonus et des PVs.<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-9805\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31.jpg\" alt=\"891 DoW 3\" width=\"650\" height=\"488\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31-300x225.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31-160x120.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31-326x245.jpg 326w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-31-453x340.jpg 453w\" sizes=\"auto, (max-width: 650px) 100vw, 650px\" \/><\/a>Quand tout le monde a plac\u00e9 ses figurines et soldats, on regarde les familles victorieuses et les joueurs qui les ont soutenues gagnent des PVs (1 PV\/figurine en soutien) et le joueur majoritaire en figurine gagne un bonus suppl\u00e9mentaire.\u00a0 De plus, ces familles victorieuses voient leur marqueur \u00e9voluer sur une \u00e9chelle qui rapportera des PVs aux joueurs ayant choisi leur blason comme bonus au placement de leur figurine.<\/p>\n<p>Comme toujours chez <a href=\"http:\/\/www.vindjeu.eu\/editeurs\/edge-entertainment\/\" target=\"_blank\">Edge<\/a>, le th\u00e8me fait partie int\u00e9grante du jeu et contribue au plaisir d\u2019y jouer.\u00a0 Il est d\u2019ailleurs introduit dans les r\u00e8gles par une superbe lettre testamentaire et les 15 derni\u00e8res pages expliquent en d\u00e9tail l\u2019historique des personnages incarn\u00e9s par les joueurs ainsi que les diff\u00e9rentes familles dont les traditions &amp; technologies sont expliqu\u00e9es en longueur.\u00a0 C\u2019est digne d\u2019un jeu de r\u00f4le et les joueurs qui affectionnent ce type de lecture s\u2019en d\u00e9lecteront.\u00a0 De plus, le mat\u00e9riel est unique, magnifique et contribue pour beaucoup au plaisir ludique. \u00a0Dans ce th\u00e8me m\u00e9di\u00e9val-fantastique-steam punk, les Dogs of War, autrement dit les Chiens de Guerre, sont g\u00e9r\u00e9s par les joueurs et repr\u00e9sentent des \u00ab\u00a0\u00e9lectrons\u00a0libres\u00a0\u00bb qui vont aider les diff\u00e9rentes familles dans leurs batailles.\u00a0 Ce sont des \u00e9lectrons libres car ils ne sont pas li\u00e9s \u00e0 une famille mais soutiendront celle(s) de leur choix.\u00a0 Ils poss\u00e8dent leur propre histoire et leurs propres atouts apportant des pouvoirs sp\u00e9cifiques et uniques \u00e0 chaque joueur et donnant un c\u00f4t\u00e9 asym\u00e9trique au jeu qui colle aussi bien au th\u00e8me qu\u2019aux m\u00e9canismes.<\/p>\n<p>L\u2019interaction est le c\u0153ur m\u00eame de la m\u00e9canique de Dogs of War.\u00a0 Le jeu en lui-m\u00eame est assez simple\u00a0et les choix restreints\u00a0qui se limitent \u00e0 choisir quel camps on veut soutenir et sur quelle case on place sa figurine.\u00a0 Dogs of War est \u00e9galement assez lin\u00e9aire durant ses 4 manches.\u00a0 Tout le sel du jeu vient de son ouverture \u00e0 la diplomatie des joueurs qui vont tr\u00e8s rapidement d\u00e9lier leur langue pour influencer, convaincre, s\u2019associer, trahir, se venger dans une ambiance parfois tendue mais souvent joyeuse, surprenante et bon enfant.<\/p>\n<p style=\"text-align: center;\">____________________________________________________________________________________<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-9802\" src=\"http:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4.jpg\" alt=\"891 DoW 4\" width=\"1024\" height=\"667\" srcset=\"https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4.jpg 1024w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4-300x195.jpg 300w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4-160x104.jpg 160w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4-376x245.jpg 376w, https:\/\/www.vindjeu.eu\/prd\/wp-content\/uploads\/2014\/12\/891-DoW-4-521x340.jpg 521w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p> Dogs of War est le dernier jeu de Paolo Mori, l\u2019auteur du g\u00e9nialissime Vasco Da Gama (un de nos coups de coeur 2010) et des tr\u00e8s sympas Augustus &amp; Libertalia. Depuis Vasco, l\u2019orientation ludique de Paolo est plut\u00f4t tourn\u00e9e vers le familial \/ familial +.\u00a0 Et Dogs of&#46;&#46;&#46;<\/p>\n","protected":false},"author":3,"featured_media":9803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[4848],"tags":[7],"class_list":["post-9801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-initie","tag-swatsh","annee-779","auteurs-paolo-mori","editeurs-edge-entertainment"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/9801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/comments?post=9801"}],"version-history":[{"count":0,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/posts\/9801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media\/9803"}],"wp:attachment":[{"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/media?parent=9801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/categories?post=9801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vindjeu.eu\/prd\/wp-json\/wp\/v2\/tags?post=9801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}